{"id":11377,"date":"2018-12-13T23:19:23","date_gmt":"2018-12-14T02:19:23","guid":{"rendered":"http:\/\/www.legistdf.gob.ar\/?p=11377"},"modified":"2018-12-13T23:19:23","modified_gmt":"2018-12-14T02:19:23","slug":"boletin-de-asuntos-entrados-bae-y-orden-del-dia-od-2","status":"publish","type":"post","link":"https:\/\/www.legistdf.gob.ar\/index.php\/2018\/12\/13\/boletin-de-asuntos-entrados-bae-y-orden-del-dia-od-2\/","title":{"rendered":"BOLET\u00cdN DE ASUNTOS ENTRADOS (BAE) Y ORDEN DEL D\u00cdA (OD)"},"content":{"rendered":"<p>Buenas noches, a continuaci\u00f3n adjunto Bolet\u00edn de Asuntos Entrados (BAE) y Orden del d\u00eda (OD) para la novena sesi\u00f3n ordinaria del Parlamento fueguino, que se concretar\u00e1 ma\u00f1ana viernes desde las 16 en el recinto de sesiones de Yaganes y H\u00e9roes de Malvinas. Ambos documentos han sido producidos, luego de la reuni\u00f3n de la Comisi\u00f3n de Labor Parlamentaria de hoy, jueves.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/12\/09bo1412.rtf-1.docx\">09bo1412.rtf<\/a><\/p>\n<p><a href=\"http:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/12\/09or1412.rtf-1.doc\">09or1412.rtf<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>TSCS Andr\u00e9s Toledo<\/strong><\/p>\n<p><strong>Director de Prensa<\/strong><\/p>\n<p><strong>y Difusi\u00f3n Institucional<\/strong><\/p>\n<p><strong>Legislatura de Tierra del Fuego<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenas noches, a continuaci\u00f3n adjunto Bolet\u00edn de Asuntos Entrados (BAE) y Orden del d\u00eda (OD) para la novena sesi\u00f3n ordinaria del Parlamento fueguino, que se concretar\u00e1 ma\u00f1ana viernes desde las 16 en el recinto de sesiones de Yaganes y H\u00e9roes de Malvinas. Ambos documentos han sido producidos, luego de la reuni\u00f3n de la Comisi\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":352,"featured_media":9827,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-11377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/09\/IMG_2035.jpg","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/11377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/352"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=11377"}],"version-history":[{"count":1,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/11377\/revisions"}],"predecessor-version":[{"id":11380,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/11377\/revisions\/11380"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media\/9827"}],"wp:attachment":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=11377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=11377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=11377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}