{"id":16749,"date":"2019-11-12T17:07:14","date_gmt":"2019-11-12T20:07:14","guid":{"rendered":"http:\/\/www.legistdf.gob.ar\/?p=16749"},"modified":"2019-11-12T17:07:14","modified_gmt":"2019-11-12T20:07:14","slug":"presupuesto-no-puedo-hacer-mas-que-insistir-y-nadie-quiere-concurrir-dijo-pablo-blanco","status":"publish","type":"post","link":"https:\/\/www.legistdf.gob.ar\/index.php\/2019\/11\/12\/presupuesto-no-puedo-hacer-mas-que-insistir-y-nadie-quiere-concurrir-dijo-pablo-blanco\/","title":{"rendered":"PRESUPUESTO: \u201cNo puedo hacer m\u00e1s que insistir y nadie quiere concurrir\u201d dijo Pablo Blanco"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-16754 size-medium alignright\" src=\"http:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0261-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0261-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0261-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0261-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0261.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Ushuaia, martes 12 de noviembre de 2019.- La Comisi\u00f3n de Presupuesto se reuni\u00f3 esta tarde, sin embargo se confirm\u00f3 la inasistencia de funcionarios gubernamentales, quienes deb\u00edan dar cuenta del proyecto de Presupuesto para 2020. El titular de la Comisi\u00f3n N\u00ba 2, Pablo Blanco lament\u00f3 el env\u00edo de una nota por parte del jefe de Gabinete \u201cdiciendo que no iban a concurrir, que iban a mandar informaci\u00f3n\u201d. Agreg\u00f3: \u201cComo presidente de la Comisi\u00f3n, no puedo hacer m\u00e1s que insistir y nadie quiere concurrir. Ac\u00e1 termina mi funci\u00f3n\u201d, dijo a Prensa Legislativa.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Previo al inicio del encuentro, donde se debati\u00f3 la situaci\u00f3n del proyecto Presupuesto 2020, los Legisladores recibieron a referentes sindicales de la Asociaci\u00f3n de Trabajadores del Estado (ATE) y\u00a0 de la Asociaci\u00f3n Fueguina de Empleados P\u00fablicos (<em>AFEP<\/em>) quienes entregaron un petitorio a la Comisi\u00f3n. En \u00e9l, solicitan la conformaci\u00f3n de una mesa de di\u00e1logo con el Ejecutivo, ante al crisis econ\u00f3mica que atraviesa la Provincia, en especial el sector. Desde la Comisi\u00f3n, adelantaron que la semana entrante tendr\u00e1n una respuesta sobre la gesti\u00f3n solicitada desde los trabajadores estatales.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Respecto del tratamiento del proyecto de Presupuesto, Blanco afirm\u00f3 que, entre los Parlamentarios reunidos hoy, \u201ctomamos la decisi\u00f3n de no darle continuidad\u201d, habida cuenta que los funcionarios no quieren llegar a San Mart\u00edn 1431. Tambi\u00e9n inform\u00f3 que las autoridades electas \u201cno necesitan este proyecto de Presupuesto 2020 y que van a trabajar con uno reconducido\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Al resumir, Blanco evalu\u00f3 que no tiene sentido \u201ccontinuar insistiendo en tratar el Presupuesto 2020\u201d y aclar\u00f3 que \u201cquedar\u00e1 en Comisi\u00f3n hasta que la nueva Legislatura asuma\u201d y determine qu\u00e9 hacer con \u00e9l.<\/p>\n<p>&nbsp;<\/p>\n<p>Consultado sobre la situaci\u00f3n institucional y pol\u00edtica de esta decisi\u00f3n, Blanco consider\u00f3 que \u201cde no aprobarse un proyecto de Presupuesto antes del 31 de diciembre, se iniciar\u00e1 la nueva gesti\u00f3n de gobierno con un presupuesto reconducido de otro reconducido\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Aclar\u00f3 adem\u00e1s que, al no contar con el texto sancionado, \u201cno hay enfocado, nada de su plan de Gobierno. Lo \u00fanico que van a poder hacer, y con suerte, es pagar sueldos los primeros meses\u201d, se\u00f1al\u00f3 en su despacho de los bloques pol\u00edticos. Cabe destacar, que no hay \u201cnada incluido de su plan de Gobierno en el Presupuesto que deber\u00e1 ser reconducido\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Tambi\u00e9n, se aventur\u00f3 en considerar que otro proyecto puede ser aprobado entre el 17 y 31 de diciembre pr\u00f3ximo: \u201cSeguramente ellos estar\u00e1n prepar\u00e1ndolo y lo tratar\u00e1n en la nueva Legislatura\u201d. En esta composici\u00f3n parlamentaria \u201cvamos a terminar el periodo de sesiones, sin el tratamiento del proyecto\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><em>DICTAMEN SOBRE ASOCIACI\u00d3N REENCONTR\u00c1NDONOS<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-16751 size-medium\" src=\"http:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0256-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0256-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0256-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0256-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0256.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Con posterioridad, los Parlamentarios recibieron a la titular de la Asociaci\u00f3n Reencontr\u00e1ndonos, Stella Maris Lavenia y dictaminaron sobre el asunto que busca mantener en funcionamiento la instituci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>El texto del <a href=\"http:\/\/www.legistdf.gob.ar\/lp\/novedadesip\/Asuntos%20Entrados%202019\/As.%20N%BA%20249-19.pdf\">asunto N\u00ba 249\/19<\/a>, de once \u00edtems, busca hacer frente\u00a0 al pago de salarios y honorarios de personal \u201cadministrativo y de profesionales\u201d que prestan servicios en la asociaci\u00f3n civil con sede en Ushuaia y R\u00edo Grande.<\/p>\n<p>&nbsp;<\/p>\n<p>Al presentar la iniciativa, Stella Maris Lavenia, hizo un repaso de la historia de la instituci\u00f3n con la caracterizaci\u00f3n del consumo de drogas, al que calific\u00f3 de presencia cruda en \u201cnuestra sociedad y es el Estado quien debe garantizar a la comunidad la posibilidad de salir de este flagelo que no discrimina clases sociales\u201d, dice entre los fundamentos.\u00a0 En otro apartado del mensaje, sostiene que nuestra Provincia ha dejado de ser un \u201clugar de paso, para transformarse en una de consumo\u201d.<\/p>\n<p>De la reuni\u00f3n, participaron Pablo Blanco, M\u00f3nica Urquiza, Myriam Mart\u00ednez, Andrea Freites, Liliana MArt\u00ednez Allende y Federico Bilota.<\/p>\n<p style=\"text-align: right\"><em>AT-DM<\/em><\/p>\n<p>&nbsp;<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-16749 gallery-columns-3 gallery-size-medium'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2019\/11\/12\/presupuesto-no-puedo-hacer-mas-que-insistir-y-nadie-quiere-concurrir-dijo-pablo-blanco\/img_0253-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0253-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0253-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0253-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0253-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0253.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2019\/11\/12\/presupuesto-no-puedo-hacer-mas-que-insistir-y-nadie-quiere-concurrir-dijo-pablo-blanco\/img_0256-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0256-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0256-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0256-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0256-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0256.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2019\/11\/12\/presupuesto-no-puedo-hacer-mas-que-insistir-y-nadie-quiere-concurrir-dijo-pablo-blanco\/img_0258-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0258-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0258-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0258-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0258-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0258.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2019\/11\/12\/presupuesto-no-puedo-hacer-mas-que-insistir-y-nadie-quiere-concurrir-dijo-pablo-blanco\/img_0261\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0261-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0261-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0261-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0261-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0261.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2019\/11\/12\/presupuesto-no-puedo-hacer-mas-que-insistir-y-nadie-quiere-concurrir-dijo-pablo-blanco\/img_0262\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0262-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0262-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0262-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0262-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0262.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2019\/11\/12\/presupuesto-no-puedo-hacer-mas-que-insistir-y-nadie-quiere-concurrir-dijo-pablo-blanco\/img_0264\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0264-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0264-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0264-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0264-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0264.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2019\/11\/12\/presupuesto-no-puedo-hacer-mas-que-insistir-y-nadie-quiere-concurrir-dijo-pablo-blanco\/img_0267-4\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0267-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0267-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0267-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0267-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0267.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2019\/11\/12\/presupuesto-no-puedo-hacer-mas-que-insistir-y-nadie-quiere-concurrir-dijo-pablo-blanco\/img_0270-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0270-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0270-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0270-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0270-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0270.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Ushuaia, martes 12 de noviembre de 2019.- La Comisi\u00f3n de Presupuesto se reuni\u00f3 esta tarde, sin embargo se confirm\u00f3 la inasistencia de funcionarios gubernamentales, quienes deb\u00edan dar cuenta del proyecto de Presupuesto para 2020. El titular de la Comisi\u00f3n N\u00ba 2, Pablo Blanco lament\u00f3 el env\u00edo de una nota por parte del jefe de Gabinete [&hellip;]<\/p>\n","protected":false},"author":352,"featured_media":16754,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"PRESUPUESTO: \u201cNo puedo hacer m\u00e1s que insistir y nadie quiere concurrir\u201d dijo Pablo Blanco #TierradelFuego #Ushuaia #LegisTDF","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[83,86,79,87],"class_list":["post-16749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa","tag-pablo-blanco","tag-presupuesto","tag-tierra-del-fuego","tag-ushuaia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0261.jpg","_links":{"self":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/16749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/352"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=16749"}],"version-history":[{"count":2,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/16749\/revisions"}],"predecessor-version":[{"id":16761,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/16749\/revisions\/16761"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media\/16754"}],"wp:attachment":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=16749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=16749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=16749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}