{"id":16769,"date":"2019-11-13T18:17:16","date_gmt":"2019-11-13T21:17:16","guid":{"rendered":"http:\/\/www.legistdf.gob.ar\/?p=16769"},"modified":"2019-11-13T18:17:20","modified_gmt":"2019-11-13T21:17:20","slug":"comision-2-dictaminaron-sobre-ley-de-creacion-del-btf-sa","status":"publish","type":"post","link":"https:\/\/www.legistdf.gob.ar\/index.php\/2019\/11\/13\/comision-2-dictaminaron-sobre-ley-de-creacion-del-btf-sa\/","title":{"rendered":"Comisi\u00f3n 2: Dictaminaron sobre ley de creaci\u00f3n del BTF SA"},"content":{"rendered":"<p><strong>Mi\u00e9rcoles 13 de noviembre de 2019.- \u201cTodos estamos de acuerdo en que el Banco de Tierra del Fuego contin\u00fae siendo 100% propiedad estatal\u201d dijo, esta tarde al finalizar el encuentro de la Comisi\u00f3n N\u00ba 2, el legislador Pablo Blanco. Luego de la exposici\u00f3n de Gabriel Clementino, vicepresidente de la entidad y Esteban Olmo, referente de la Asociaci\u00f3n Bancaria, los Parlamentarios dictaminaron sobre el asunto que busca derogar la Ley provincial N\u00ba 478. En la mesa de trabajo, se expuso \u201cunanimidad de criterios de todos los Legisladores\u201d. <\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>El titular de la Comisi\u00f3n de Presupuesto dijo que se aguardan los lineamientos t\u00e9cnicos para \u201credactar el dictamen y que se deje sin efecto la Ley N\u00ba 478 y que no tenga implicancias en el funcionamiento de la instituci\u00f3n\u201d, se\u00f1al\u00f3 este mediod\u00eda a Prensa Legislativa.<\/p>\n<p>&nbsp;<\/p>\n<p>La Ley de transformaci\u00f3n del BTF en sociedad an\u00f3nima fue sancionada en marzo de hace 19 a\u00f1os y buscaba constituir una sociedad an\u00f3nima regida por las disposiciones de las Leyes N\u00ba 19.550 y 21.526. El texto, determinaba que tendr\u00eda \u201cuna duraci\u00f3n de noventa y nueve a\u00f1os, contados a partir de la fecha de su inscripci\u00f3n en el Registro P\u00fablico de Comercio\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Blanco aclar\u00f3 que el dictamen sobre el particular, ser\u00e1 tratado en la pr\u00f3xima sesi\u00f3n ordinaria del Parlamento fueguino.<\/p>\n<p>&nbsp;<\/p>\n<p>Por su parte, el contador Gabriel Clementino consider\u00f3 que \u201cse sanea una situaci\u00f3n que nunca se hab\u00eda hecho operativa\u201d en alusi\u00f3n a la Ley en cuesti\u00f3n. \u201cEs una norma de hace 19 a\u00f1os y nunca se hab\u00eda hecho nada\u201d, el vicepresidente de la entidad agreg\u00f3 que se genera una \u201cinseguridad jur\u00eddica\u201d a los empleados y cuestion\u00f3 \u201cel contexto en el que se hab\u00eda aprobado esa norma\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>En el encuentro con los legisladores, miembros del BTF reflejaron ese contexto econ\u00f3mico y entendieron que \u201cha sido un an\u00e1lisis muy objetivo\u201d por parte de la conformaci\u00f3n parlamentaria.<\/p>\n<p>&nbsp;<\/p>\n<p>Clementino destac\u00f3 \u201cla buena voluntad y fe\u201d y se pregunt\u00f3 el sentido de conservar una norma que plantea \u201cuna puerta a un lugar que no tiene ese escenario\u201d econ\u00f3mico. \u201cEl escenario de una privatizaci\u00f3n no existe, o de una sociedad privada no est\u00e1. Hac\u00eda a la seguridad jur\u00eddica del banco, como marca y como empresa\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Al finalizar, el funcionario dijo que en la mesa de trabajo se garantiz\u00f3 \u201cque la visi\u00f3n del Gobierno electo, no es la privatizaci\u00f3n\u201d algo que ya hab\u00eda sido expresado oportunamente, cerr\u00f3.<\/p>\n<p>&nbsp;<\/p>\n<p>En tanto, Estaban Olmo, referente de la Asociaci\u00f3n bancaria dijo que \u201ces positivo para nosotros\u201d el tratamiento del proyecto de derogaci\u00f3n de la Ley Provincial N\u00ba 478.<\/p>\n<p>&nbsp;<\/p>\n<p>Desde el sector, afirm\u00f3 que \u201csi bien no hay una intenci\u00f3n directa de privatizar el Banco o hacerlo una sociedad an\u00f3nima, como manifest\u00f3 la legisladora M\u00f3nica Urquiza\u201d donde la nueva gesti\u00f3n \u201cno tiene intenciones en este sentido, no deja de ser un riesgo potencial tener una Ley que es aplicable\u201d, resumi\u00f3.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right\"><em>AT<\/em><\/p>\n<p>[youtube https:\/\/www.youtube.com\/watch?v=oqpAzebU47I&amp;w=853&amp;h=480]<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-16769 gallery-columns-3 gallery-size-medium'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2019\/11\/13\/comision-2-dictaminaron-sobre-ley-de-creacion-del-btf-sa\/img_0275\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0275-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0275-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0275-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0275-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0275.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2019\/11\/13\/comision-2-dictaminaron-sobre-ley-de-creacion-del-btf-sa\/img_0302-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0302-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0302-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0302-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0302-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0302.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2019\/11\/13\/comision-2-dictaminaron-sobre-ley-de-creacion-del-btf-sa\/img_0303-5\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0303-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0303-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0303-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0303-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0303.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2019\/11\/13\/comision-2-dictaminaron-sobre-ley-de-creacion-del-btf-sa\/img_0304\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0304-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0304-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0304-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0304-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0304.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2019\/11\/13\/comision-2-dictaminaron-sobre-ley-de-creacion-del-btf-sa\/img_0307-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0307-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0307-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0307-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0307-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0307.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2019\/11\/13\/comision-2-dictaminaron-sobre-ley-de-creacion-del-btf-sa\/img_0312\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0312-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0312-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0312-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0312-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0312.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2019\/11\/13\/comision-2-dictaminaron-sobre-ley-de-creacion-del-btf-sa\/img_0314\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0314-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0314-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0314-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0314-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0314.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2019\/11\/13\/comision-2-dictaminaron-sobre-ley-de-creacion-del-btf-sa\/img_0328-4\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0328-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0328-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0328-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0328-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0328.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2019\/11\/13\/comision-2-dictaminaron-sobre-ley-de-creacion-del-btf-sa\/img_0337-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0337-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0337-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0337-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0337-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0337.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2019\/11\/13\/comision-2-dictaminaron-sobre-ley-de-creacion-del-btf-sa\/img_0348\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0348-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0348-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0348-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0348-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0348.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2019\/11\/13\/comision-2-dictaminaron-sobre-ley-de-creacion-del-btf-sa\/img_0352-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0352-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0352-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0352-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0352-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0352.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2019\/11\/13\/comision-2-dictaminaron-sobre-ley-de-creacion-del-btf-sa\/img_0365\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0365-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0365-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0365-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0365-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0365.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mi\u00e9rcoles 13 de noviembre de 2019.- \u201cTodos estamos de acuerdo en que el Banco de Tierra del Fuego contin\u00fae siendo 100% propiedad estatal\u201d dijo, esta tarde al finalizar el encuentro de la Comisi\u00f3n N\u00ba 2, el legislador Pablo Blanco. Luego de la exposici\u00f3n de Gabriel Clementino, vicepresidente de la entidad y Esteban Olmo, referente de [&hellip;]<\/p>\n","protected":false},"author":352,"featured_media":16770,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"Comisi\u00f3n 2: Dictaminaron sobre ley de creaci\u00f3n del BTF SA #Ushuaia #TierradelFuego #LegisTDF","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[426,600,1743,78,79,87],"class_list":["post-16769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa","tag-btf","tag-comision","tag-dictamen","tag-legislatura","tag-tierra-del-fuego","tag-ushuaia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/11\/IMG_0275.jpg","_links":{"self":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/16769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/352"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=16769"}],"version-history":[{"count":4,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/16769\/revisions"}],"predecessor-version":[{"id":16798,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/16769\/revisions\/16798"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media\/16770"}],"wp:attachment":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=16769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=16769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=16769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}