{"id":18115,"date":"2020-01-02T11:14:57","date_gmt":"2020-01-02T14:14:57","guid":{"rendered":"http:\/\/www.legistdf.gob.ar\/?p=18115"},"modified":"2020-01-02T11:14:57","modified_gmt":"2020-01-02T14:14:57","slug":"emergencia-debemos-generar-procedimientos-transparentes-para-garantizar-el-rol-del-estado-explico-vuoto","status":"publish","type":"post","link":"https:\/\/www.legistdf.gob.ar\/index.php\/2020\/01\/02\/emergencia-debemos-generar-procedimientos-transparentes-para-garantizar-el-rol-del-estado-explico-vuoto\/","title":{"rendered":"Emergencia: \u201cDebemos generar procedimientos transparentes para garantizar el rol del Estado\u201d explic\u00f3 Vuoto"},"content":{"rendered":"<p><em style=\"text-align: right\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-18069 size-medium\" src=\"http:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/12\/IMG_1814-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/12\/IMG_1814-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/12\/IMG_1814-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/12\/IMG_1814-1024x683.jpg 1024w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/12\/IMG_1814-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/12\/IMG_1814.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/em><\/p>\n<p><strong>Ushuaia, jueves 2 de enero de 2020.- Luego de \u201cmucha controversia\u201d, se llev\u00f3 a cabo la sesi\u00f3n extraordinaria, el viernes pasado, donde se analiz\u00f3 el paquete de leyes de Emergencia planteado por el gobernador Gustavo Melella.\u00a0 <\/strong><strong>Desde el Partido Verde, plantearon su preocupaci\u00f3n y los tres legisladores del bloque decidieron no acompa\u00f1ar la emergencia previsional, la emergencia portuaria y se opusieron fuertemente a la emergencia administrativa junto a otros Legisladores lograron que no se trate. \u201cEl objetivo que se declara nada tiene que ver con las medidas que se proponen, que buscan otorgarle amplias facultades al Poder Ejecutivo reduciendo los controles de la Legislatura, e incluso de la sociedad, sobre el manejo de los fondos p\u00fablicos\u201d, explic\u00f3 la legisladora Vuoto.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Respecto de la Ley de emergencia en infraestructura portuaria, Vuoto argument\u00f3 que desde el Partido Verde \u201cno acompa\u00f1amos lo que han consensuado el resto de los bloques porque la situaci\u00f3n que atraviesa el puerto en nada se parece a una emergencia. No est\u00e1 en peligro la operatividad del muelle, ni log\u00edstico, ni tur\u00edstico para esta temporada. En el proyecto aprobado se dejan de lado todos los principios b\u00e1sicos donde la regla es la licitaci\u00f3n p\u00fablica\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>El\u00a0Partido Verde s\u00ed acompa\u00f1\u00f3 la emergencia en infraestructura educativa e incorporaron modificaciones que ayudar\u00e1n a agilizar los plazos para comenzar las clases en marzo. La legisladora Victoria Vuoto explic\u00f3 que \u201cmantiene los controles adecuados en los procedimientos administrativos, permitiendo lograr procedimientos en funci\u00f3n de las necesidades objetivas que tienen los establecimientos de R\u00edo Grande, Tolhuin y Ushuaia.\u201d Aunque tambi\u00e9n manifest\u00f3 su especial preocupaci\u00f3n por el rol que tendr\u00e1n los\u00a0espacios educativos como lugares de contenci\u00f3n social para los m\u00e1s vulnerables en este momento \u201cde gran complejidad\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right\"><em>Gentileza Prensa Bloque PV<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ushuaia, jueves 2 de enero de 2020.- Luego de \u201cmucha controversia\u201d, se llev\u00f3 a cabo la sesi\u00f3n extraordinaria, el viernes pasado, donde se analiz\u00f3 el paquete de leyes de Emergencia planteado por el gobernador Gustavo Melella.\u00a0 Desde el Partido Verde, plantearon su preocupaci\u00f3n y los tres legisladores del bloque decidieron no acompa\u00f1ar la emergencia previsional, [&hellip;]<\/p>\n","protected":false},"author":352,"featured_media":18046,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"Emergencia: \u201cDebemos generar procedimientos transparentes para garantizar el rol del Estado\u201d explic\u00f3 Vuoto #NuevaLegislaturaTDF #Ushuaia #TierradelFuego #LegisTDF","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[78,79,87,1822],"class_list":["post-18115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa","tag-legislatura","tag-tierra-del-fuego","tag-ushuaia","tag-victoria-vuoto"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2019\/12\/IMG_1765.jpg","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/18115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/352"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=18115"}],"version-history":[{"count":1,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/18115\/revisions"}],"predecessor-version":[{"id":18116,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/18115\/revisions\/18116"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media\/18046"}],"wp:attachment":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=18115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=18115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=18115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}