{"id":21094,"date":"2020-09-09T14:39:45","date_gmt":"2020-09-09T17:39:45","guid":{"rendered":"http:\/\/www.legistdf.gob.ar\/?p=21094"},"modified":"2020-09-09T14:39:45","modified_gmt":"2020-09-09T17:39:45","slug":"comisiones-lenguaje-de-senas-pasantias-educativas-y-cambio-climatico-en-la-agenda-legislativa","status":"publish","type":"post","link":"https:\/\/www.legistdf.gob.ar\/index.php\/2020\/09\/09\/comisiones-lenguaje-de-senas-pasantias-educativas-y-cambio-climatico-en-la-agenda-legislativa\/","title":{"rendered":"COMISIONES: Lenguaje de se\u00f1as, pasant\u00edas educativas y cambio clim\u00e1tico en la agenda legislativa"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-21008 size-medium\" src=\"http:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/11-1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/11-1-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/11-1-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/11-1-1024x683.jpg 1024w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/11-1-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/11-1.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Ushuaia, mi\u00e9rcoles 9 de septiembre de 2020.- El Presidente de la Comisi\u00f3n de Educaci\u00f3n N\u00b0 4, legislador Emmanuel Trentino (FORJA) convoc\u00f3 a los Parlamentarios integrantes de ese espacio a una reuni\u00f3n para el pr\u00f3ximo jueves 10 a las 15 h. All\u00ed abordar\u00e1n distintos asuntos que se encuentran en agenda parlamentaria, entre los que se destacan proyectos de Ley y declaraciones de inter\u00e9s provincial.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><em>AMBIENTE: Proponen regular acciones para mitigar efectos del cambio clim\u00e1tico<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>En marzo de 2019, el bloque UCR \u2013 Cambiemos present\u00f3 un proyecto de Ley que busca \u201cestablecer las acciones, instrumentos, mecanismos y estrategias adecuadas de adaptaci\u00f3n y mitigaci\u00f3n al Cambio Clim\u00e1tico en la Provincia de Tierra del Fuego, Ant\u00e1rtida e Islas del Atl\u00e1ntico Sur, para reducir la vulnerabilidad humana y de los ecosistemas y biomas, a fin de protegerlos para evitar efectos adversos y aprovechar sus beneficios de manera sustentable\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>En los fundamentos del asunto, registrado bajo el N\u00ba 039\/19, los Parlamentarios sostienen que \u201clas emisiones de gases de efecto invernadero est\u00e1n cambiando la condici\u00f3n clim\u00e1tica del planeta a un ritmo acelerado; ello repercute negativamente en nuestro h\u00e1bitat, con las consecuentes transformaciones del paisaje, afectaci\u00f3n de cuencas h\u00eddricas y cambios bruscos en la atm\u00f3sfera, que alteran las condiciones de supervivencia tanto en las aguas como en la superficie del planeta\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>La norma propuesta busca dise\u00f1ar, implementar y proyectar pol\u00edticas de Estado en materia de adaptaci\u00f3n y mitigaci\u00f3n al cambio clim\u00e1tico para las generaciones presentes y futuras; integrar pol\u00edticas, estrategias y medidas de mitigaci\u00f3n y adaptaci\u00f3n a los procesos claves de planificaci\u00f3n; incorporar el concepto de riesgos clim\u00e1ticos futuros, su monitoreo y el manejo de riesgos, para la formulaci\u00f3n de pol\u00edticas y planes; reducir las emisiones de gases de efecto invernadero en el \u00e1mbito de la Provincia; preparar a la administraci\u00f3n p\u00fablica y de la sociedad en general, ante el posible impacto de cambios clim\u00e1ticos futuros, entre otras.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><em>INCLUSI\u00d3N: Talleres de lenguaje de se\u00f1as en las escuelas<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>El mismo bloque present\u00f3 tambi\u00e9n, en agosto del a\u00f1o pasado, el asunto registrado bajo el N\u00ba 233\/19, que busca incorporar \u201cen el Sistema de Educaci\u00f3n de la Provincia de Tierra del Fuego, talleres sobre el Lenguaje de Se\u00f1as Argentina\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>El proyecto de Ley propone\u00a0 \u201cincluir en el sistema educativo talleres que tiendan a la inclusi\u00f3n de las personas con disminuciones auditivas, sordos e hipoac\u00fasicos, a trav\u00e9s de la lengua de se\u00f1as\u201d. En los fundamentos, los Parlamentarios impulsores de la norma sostienen que, en Argentina hay n\u00famero mayor a 70.000 sordos y m\u00e1s de 450.000 personas con alguna discapacidad auditiva, \u201cpor ello vemos importante poder trabajar al respecto\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><em>CULTURA: La actividad coral como herramienta educativa.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>Los Legisladores integrantes de la Comisi\u00f3n de Educaci\u00f3n abordar\u00e1n tambi\u00e9n el asunto N\u00ba 278\/19, \u201cproyecto de Ley de fomento a la actividad coral en el \u00e1mbito de la Provincia\u201d. La norma fue presentada por el Ejecutivo provincial en septiembre de 2019.<\/p>\n<p>&nbsp;<\/p>\n<p>All\u00ed se afirma que \u201cla actividad coral constituye uno de los pilares fundamentales en la cultura de las sociedades, fomentando y permitiendo el desarrollo y educaci\u00f3n de los pueblos. El canto coral ha sido una de las manifestaciones m\u00e1s antiguas del ser humano, en su necesidad de expresar sus sentimientos y vivencias en forma colectiva, a trav\u00e9s del instrumento m\u00e1s cercano e inmediato que posee: su propia voz\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>El proyecto propone declarar de inter\u00e9s cultural la creaci\u00f3n y funcionamiento de conjuntos y\/o entidades corales sin fines de lucro en todo el territorio provincial. Tambi\u00e9n declara al Coro del Fin del Mundo como \u00abCoro Oficial de la Provincia de Tierra del Fuego, Ant\u00e1rtida e Islas del Atl\u00e1ntico Sur\u00bb, en reconocimiento a la amplia labor desarrollada a favor de la actividad coral en la Provincia.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><em>INTER\u00c9S PROVINCIAL: El Partido Verde impulsa dos declaraciones<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>El bloque del Partido Verde impulsa declarar de inter\u00e9s provincial el proyecto \u201cActualizaci\u00f3n e implementaci\u00f3n de dispositivos educativos basados en modelos de simulaci\u00f3n de epidemias\u201d, generado desde el Instituto de Desarrollo Econ\u00f3mico e Innovaci\u00f3n de la Universidad Nacional de Tierra del Fuego (UNTDF) y la Facultad Regional Tierra del Fuego de la Universidad Tecnol\u00f3gica Nacional (UTN).<\/p>\n<p>&nbsp;<\/p>\n<p>El proyecto tiene como objetivo \u201cgenerar un comportamiento responsable de la poblaci\u00f3n frente a las indicaciones de las autoridades sanitarias, mediante la comprensi\u00f3n de los diferentes escenarios que se desprenden de un modelo de simulaci\u00f3n de epidemias\u201d. Para ello propone el uso de herramientas de simulaci\u00f3n para interpretar el comportamiento humano sobre el desarrollo de una epidemia.<\/p>\n<p>&nbsp;<\/p>\n<p>El mismo bloque pol\u00edtico propone tambi\u00e9n declarar de inter\u00e9s provincial el documental web \u201cEl nuevo fin del mundo\u201d, realizado por Luj\u00e1n Agusti y Nicol\u00e1s Deluca, ambos habitantes de Tierra del Fuego. Por ello impulsan \u201creconocer y distinguir la labor realizada por los autores, que constituye un est\u00edmulo para todos los j\u00f3venes de la Provincia a participar de las actividades art\u00edsticas y culturales\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cEl documental brinda una narrativa audio visual a trav\u00e9s de la fotograf\u00eda y el video, que explora el rastro generado por la pandemia en la Provincia de Tierra del Fuego y c\u00f3mo nuestros seres queridos y la naturaleza, se nos revelan como el amparo m\u00e1s seguro, implicando un sentimiento de esperanza y fe\u201d, sostienen las Parlamentarias del Partido Verde en sus fundamentos.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><em>PR\u00c1CTICAS PROFESIONALIZANTES: Freites impulsa actualizar la regulaci\u00f3n de las pasant\u00edas educativas<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>Por \u00faltimo, los Parlamentarios abordar\u00e1n el asunto N\u00ba 137\/20, impulsado por la legisladora Andrea Freites (FDT \u2013 PJ), proyecto de Ley de pasant\u00edas educativas.<\/p>\n<p>&nbsp;<\/p>\n<p>Si bien en la Provincia est\u00e1 en vigencia la Ley N\u00b0 528, \u00abPasant\u00edas del SistemabEducativo\u00bb, Freites plantea en sus fundamentos que \u201cse hace necesario repensar la misma desde la concepci\u00f3n de pr\u00e1cticas profesionalizantes, como concepto clave de pr\u00e1cticas educativas\u00bb. El proyecto en debate propone la derogaci\u00f3n de la norma vigente.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cLas pasant\u00edas educativas y las pr\u00e1cticas profesionalizantes en su conjunto, son el pilar fundamental de la formaci\u00f3n de los estudiantes, tendientes a la incursi\u00f3n de estos, en los \u00e1mbitos laborales y la vida socio-econ\u00f3mica que desarrollar\u00e1n luego de finalizados sus estudios\u201d, afirma la referente del bloque FDT &#8211; PJ.<\/p>\n<p>&nbsp;<\/p>\n<p>En el texto de la norma propuesta, define\u00a0 el t\u00e9rmino de \u00abpasant\u00edas educativas\u00bb como el \u201cuniverso de actividades educativas y formativas que realicen los estudiantes relacionadas con sus estudios, en empresas y organismos, entes p\u00fablicos, descentralizados o aut\u00e1rquicos, ONG, o empresas privadas, que se reconoce como experiencia pedag\u00f3gica. En el proyecto curricular de cada instituci\u00f3n educativa, se establecer\u00e1 su duraci\u00f3n, modalidad y obligatoriedad\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right\">LVV-AT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ushuaia, mi\u00e9rcoles 9 de septiembre de 2020.- El Presidente de la Comisi\u00f3n de Educaci\u00f3n N\u00b0 4, legislador Emmanuel Trentino (FORJA) convoc\u00f3 a los Parlamentarios integrantes de ese espacio a una reuni\u00f3n para el pr\u00f3ximo jueves 10 a las 15 h. All\u00ed abordar\u00e1n distintos asuntos que se encuentran en agenda parlamentaria, entre los que se destacan [&hellip;]<\/p>\n","protected":false},"author":352,"featured_media":20350,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[84,80,1930,78,79,87],"class_list":["post-21094","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa","tag-comisiones","tag-educacion","tag-emanuel-trentino","tag-legislatura","tag-tierra-del-fuego","tag-ushuaia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/06\/IMG_6317.jpg","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/21094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/352"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=21094"}],"version-history":[{"count":1,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/21094\/revisions"}],"predecessor-version":[{"id":21095,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/21094\/revisions\/21095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media\/20350"}],"wp:attachment":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=21094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=21094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=21094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}