{"id":21128,"date":"2020-09-09T22:37:35","date_gmt":"2020-09-10T01:37:35","guid":{"rendered":"http:\/\/www.legistdf.gob.ar\/?p=21128"},"modified":"2020-09-09T22:37:35","modified_gmt":"2020-09-10T01:37:35","slug":"salud-nutrida-agenda-de-temas-con-dictamen-y-pedidos-de-informes-para-el-ejecutivo","status":"publish","type":"post","link":"https:\/\/www.legistdf.gob.ar\/index.php\/2020\/09\/09\/salud-nutrida-agenda-de-temas-con-dictamen-y-pedidos-de-informes-para-el-ejecutivo\/","title":{"rendered":"SALUD: Nutrida agenda de temas con dictamen y pedidos de informes para el Ejecutivo"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-21080 size-medium alignright\" src=\"http:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/IMG_7061-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/IMG_7061-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/IMG_7061-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/IMG_7061-1024x683.jpg 1024w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/IMG_7061-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/IMG_7061.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Ushuaia, mi\u00e9rcoles 9 de septiembre de 2020.- La Comisi\u00f3n de salud, minoridad y familia N\u00b0 5 se reuni\u00f3 por primera vez de manera remota. En agenda se encontraban siete asuntos de los cuales, la mayor\u00eda obtuvo dictamen favorable para ser tratado en la pr\u00f3xima sesi\u00f3n ordinaria. En tanto, asuntos como pedidos de informes sobre salud mental y presupuesto, fueron enviados al Ejecutivo para conocer la postura y volver a discutirlo.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>El presidente de la Comisi\u00f3n N\u00b0 5, legislador Daniel Rivarola (FORJA) coordin\u00f3 de manera conjunta con la vicepresidenta de la Comisi\u00f3n, legisladora Liliana Mart\u00ednez Allende (UCR), el encuentro que se hizo de forma mixta, es decir, con algunos de los Legisladores en el recinto y otros de forma remota.<\/p>\n<p>&nbsp;<\/p>\n<p>El primer asunto que se trat\u00f3 fue el <a href=\"http:\/\/www.legistdf.gob.ar\/lp\/novedadesip\/Asuntos%20Entrados%202020\/As.%20N%BA%20131-20.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">N\u00b0 131\/20<\/a> sobre el uso de cannabis medicinal y sus derivados que logr\u00f3 dictamen favorable y <a href=\"http:\/\/www.legistdf.gob.ar\/index.php\/2020\/09\/09\/comisiones-dictaminaron-sobre-la-modificacion-de-la-ley-sobre-uso-medicinal-del-cannabis-y-sus-derivados\/\" target=\"_blank\" rel=\"noopener noreferrer\">fue girado a la Comisi\u00f3n de Legislaci\u00f3n General N\u00b0 1<\/a> para que contin\u00fae su an\u00e1lisis.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><em>Seguro de salud obligatorio para personas extranjeras<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Adem\u00e1s se puso en discusi\u00f3n el tratamiento de los <a href=\"http:\/\/www.legistdf.gob.ar\/lp\/novedadesip\/Asuntos%20Entrados%202019\/As.%20N%BA%20016-19.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">asuntos N\u00b0 016\/19<\/a> sobre la creaci\u00f3n de un seguro de salud obligatorio para personas extranjeras, que tiene como finalidad que quienes lleguen de otros pa\u00edses -de manera transitoria- cuenten con un seguro, que deber\u00e1 ser puesto en marcha desde el Ejecutivo y generar convenios de reciprocidad y articular de qu\u00e9 forma se har\u00e1 efectivo.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><em>Busca crear un plan estrat\u00e9gico de historias cl\u00ednicas m\u00e9dicas<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Por otra parte el <a href=\"http:\/\/www.legistdf.gob.ar\/lp\/novedadesip\/Asuntos%20Entrados%202019\/As.%20N%BA%20403-19.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">asunto N\u00b0 403\/19<\/a>, sobre la creaci\u00f3n del Registro Provincial de historias cl\u00ednicas, ambos de autor\u00eda del FPV-PJ, propone mejorar y garantizar el servicio esencial de salud a trav\u00e9s de un plan estrat\u00e9gico que permita el intercambio de informaci\u00f3n entre los sectores de salud p\u00fablica y privada; el resguardo seguro y confidencial de los datos y generar un sistema de identificaci\u00f3n seguro para la implementaci\u00f3n y acceso al registro.<\/p>\n<p>&nbsp;<\/p>\n<p>Al respecto, el legislador Ricardo Furlan (FDT-PJ) argument\u00f3 durante el encuentro, que a pesar de ser necesarias estas dos herramientas, propuso enviarlas al Ejecutivo, para que puedan analizar los proyectos y realizar una devoluci\u00f3n, en el contexto de pandemia<\/p>\n<p>&nbsp;<\/p>\n<p>De acuerdo con la totalidad de los Parlamentarios, ambos proyectos de Ley se giraron al Gobierno provincial.<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-21071 size-medium alignright\" src=\"http:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/12-4-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/12-4-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/12-4-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/12-4-1024x683.jpg 1024w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/12-4-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/12-4.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>En este sentido, el presidente de la Comisi\u00f3n, adelant\u00f3 que, desde su espacio se trabaja en un proyecto que permita digitalizar las historias cl\u00ednicas y esto puede contribuir al planteo el FPV-PJ.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><em>Nuevamente en agenda legislativa la adhesi\u00f3n por muerte s\u00fabita<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Luego se dio tratamiento a los <a href=\"http:\/\/www.legistdf.gob.ar\/lp\/novedadesip\/Asuntos%20Entrados%202020\/As.%20N%BA%20095-20.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">asuntos N\u00b0 095\/20<\/a>, de autor\u00eda del MPF\u00a0que propone adherir a la Ley nacional N\u00b0 27.159 Muerte S\u00fabita &#8211; Sistema integral de prevenci\u00f3n. Esto prev\u00e9 regular un procedimiento integral de eventos por muerte s\u00fabita en espacios p\u00fablicos y privados de acceso p\u00fablico a fin de reducir la mortalidad de origen vascular.<\/p>\n<p>&nbsp;<\/p>\n<p>La Ley nacional fue sancionada en 2015 y se tiene en cuenta que la fibrilaci\u00f3n ventricular se puede definir como la contracci\u00f3n el\u00e9ctrica de las fibras card\u00edacas, pero en el tiempo e intensidad card\u00edaca pero en tiempo e intensidad distinta y la taquicardia ventricular sin pulso se define como cantidad de latidos, que ocurren a una frecuencia mayor de cien por minuto. En ambos casos el tratamiento es la desfibrilaci\u00f3n precoz.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-21064 size-medium alignleft\" src=\"http:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/4-3-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/4-3-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/4-3-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/4-3-1024x683.jpg 1024w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/4-3-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/4-3.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Las personas pueden ser salvadas del paro card\u00edaco cuando se manifiesta como una taquicardia mediante la desfibrilaci\u00f3n el\u00e9ctrica que es la terapia m\u00e1s importante con el uso de un Desfibrilador Externo Autom\u00e1tico (DEA).<\/p>\n<p>&nbsp;<\/p>\n<p>Por esto, desde el MPF fundamentan la necesidad de \u201ctrabajar en la prevenci\u00f3n integral apostando a mejorar la calidad de vida para todos los fueguinos\u201d, con la adhesi\u00f3n\u00a0 y articulaci\u00f3n de la norma nacional.<\/p>\n<p>&nbsp;<\/p>\n<p>En este sentido, la legisladora y vicepresidente de la Comisi\u00f3n, Mart\u00ednez Allende, aport\u00f3 la mirada del Legislador autor del proyecto, Pablo Villegas, quien sugiri\u00f3 enviar el proyecto de adhesi\u00f3n al Poder Ejecutivo, ya que plantea la obtenci\u00f3n de fondos e involucra a los servicios de emergencia. Adem\u00e1s, cuenta con exigencias que deben ser coordinadas con quienes deben cumplir con esta norma. Los integrantes acordaron remitir el asunto para conocimiento del Ejecutivo.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><em>Curso virtual de \u201cBuenas Pr\u00e1cticas COVID-19\u201d ser\u00e1 declarado de inter\u00e9s provincial<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Desde el Partido Verde, la legisladora Victoria Vuoto aport\u00f3 los fundamentos de los <a href=\"http:\/\/www.legistdf.gob.ar\/lp\/novedadesip\/Asuntos%20Entrados%202020\/As.%20N%BA%20099-20.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">asuntos N\u00b0 099\/20<\/a> sobre la declaraci\u00f3n de inter\u00e9s provincial el curso virtual \u201cBuenas Pr\u00e1cticas COVID-19 y el N\u00b0 123\/20 pedido de informes sobre el trabajo que realiza el equipo de Salud Mental de la Provincia.<\/p>\n<p>&nbsp;<\/p>\n<p>Asegur\u00f3, sobre el curso de \u201cBuenas Pr\u00e1cticas COVID-19\u201d, que se trata de una cuesti\u00f3n novedosa que lleva la impronta del municipio y la Universidad Nacional de Tierra del Fuego (UNTDF) como \u201cvalores ejemplares ante la sociedad y el pa\u00eds que est\u00e1 siendo capacitada tambi\u00e9n con este trabajo\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Ambas instituciones dise\u00f1aron el curso virtual gratuito de capacitaci\u00f3n para la poblaci\u00f3n local o de otras jurisdicciones, denominado \u201cBuenas Pr\u00e1cticas COVID-19\u201d, orientado a las distintas etapas de la cuarentena administrada, ya que al no haber una cura o vacuna, y convertirse en pandemia, es primordial contar con medidas efectivas de prevenci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>Esta herramienta ya lleva m\u00e1s de 5 mil inscriptos no solo en la Provincia, sino en otras de pa\u00eds.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><em>Pedido de informes sobre el trabajo en salud mental<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Otro de los asuntos abordados fue el <a href=\"http:\/\/www.legistdf.gob.ar\/lp\/novedadesip\/Asuntos%20Entrados%202020\/As.%20N%BA%20123-20.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">N\u00b0 123\/20<\/a>, pedido de informes al Gobierno sobre el plan de acci\u00f3n tomado para compatibilizar el traslado de la internaci\u00f3n de salud mental desde el Hospital Regional Ushuaia (HRU) al CAPs de Ushuaia, adem\u00e1s del trabajo que realizan con pacientes con COVID-19 y sus familias.<\/p>\n<p>&nbsp;<\/p>\n<p>El pedido responde a sondear c\u00f3mo es el plan de contingencia o reforzamiento previstos para los equipos de salud mental; acciones para contener y asistir durante la pandemia a quienes requieren el servicio de salud mental y quienes ya estaban en tratamiento, como la atenci\u00f3n telef\u00f3nica que debiera ser de 24 horas. Para garantizar la continuidad de los tratamientos y seguimientos de atenci\u00f3n ambulatoria en periodos de distanciamiento social.<\/p>\n<p>&nbsp;<\/p>\n<p>Estos asuntos fueron debatidos y consensuados por la totalidad de los Legisladores y lograron dictamen favorable para ser tratados en la pr\u00f3xima sesi\u00f3n ordinaria.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><em>La enfermedad endometriosis deber\u00e1 tener campa\u00f1as de informaci\u00f3n y difusi\u00f3n<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Otro de los asuntos debatidos y que tiene el acuerdo total de la mesa de Salud en la Legislatura, es el <a href=\"http:\/\/www.legistdf.gob.ar\/lp\/novedadesip\/Asuntos%20Entrados%202020\/As.%20N%BA%20022-20.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">asunto N\u00b0 022\/20<\/a> propuesto por el MPF que propone implementar campa\u00f1as de informaci\u00f3n y difusi\u00f3n sobre la enfermedad endometriosis, una enfermedad ginecol\u00f3gica con graves consecuencias m\u00e9dicas en caso de no ser tratada a tiempo.<\/p>\n<p>&nbsp;<\/p>\n<p>La norma busca brindar mayor visibilidad, y aportar conciencia para que m\u00e1s mujeres realicen estudios de esta \u00edndole, ya que, entre un 5 y un 10 por ciento de la poblaci\u00f3n femenina en edad reproductiva -15 a 45 a\u00f1os- padece alg\u00fan grado de endometriosis y esto afecta la fertilidad de un 30 a un 50 por ciento de los pacientes. \u201cLa Organizaci\u00f3n Mundial de la Salud (OMS) impuls\u00f3 un d\u00eda y un mes para profundizar las campa\u00f1as y debates sobre la\/patolog\u00eda\u201d, manifiestan los Legisladores en los fundamentos del asunto, que logr\u00f3 dictamen favorable.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><em>La UCR presentar\u00e1 sobre tablas proyecto de adhesi\u00f3n a Ley de Fibrosis Qu\u00edstica<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Al cerrar el encuentro, la legisladora Liliana Mart\u00ednez Allende record\u00f3 que es el mes de la Fibrosis Qu\u00edstica, una enfermedad que no tiene cura, si tratamiento. Se reprodujo un video de familiares de personas con la enfermedad para generar conciencia de la problem\u00e1tica y adelant\u00f3 que desde su espacio presentar\u00e1n sobre tablas un proyecto de Ley para lograr la adhesi\u00f3n a Ley nacional N\u00b0 27.552 sancionada por el Congreso en julio pasado.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right\"><em>MBCH-AT<\/em><\/p>\n<p>&nbsp;<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-21128 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/09\/09\/comisiones-dictaminaron-sobre-la-modificacion-de-la-ley-sobre-uso-medicinal-del-cannabis-y-sus-derivados\/2-184\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/2-4-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/2-4-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/2-4-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/09\/09\/comisiones-dictaminaron-sobre-la-modificacion-de-la-ley-sobre-uso-medicinal-del-cannabis-y-sus-derivados\/4-139\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/4-3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/4-3-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/4-3-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/09\/09\/comisiones-dictaminaron-sobre-la-modificacion-de-la-ley-sobre-uso-medicinal-del-cannabis-y-sus-derivados\/8-50\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/8-4-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/8-4-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/8-4-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/09\/09\/comisiones-dictaminaron-sobre-la-modificacion-de-la-ley-sobre-uso-medicinal-del-cannabis-y-sus-derivados\/11-23\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/11-3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/11-3-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/11-3-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/09\/09\/comisiones-dictaminaron-sobre-la-modificacion-de-la-ley-sobre-uso-medicinal-del-cannabis-y-sus-derivados\/12-17\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/12-4-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/12-4-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/12-4-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/09\/09\/comisiones-dictaminaron-sobre-la-modificacion-de-la-ley-sobre-uso-medicinal-del-cannabis-y-sus-derivados\/3-160\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/3-3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/3-3-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/3-3-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/09\/09\/comisiones-dictaminaron-sobre-la-modificacion-de-la-ley-sobre-uso-medicinal-del-cannabis-y-sus-derivados\/5-128\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/5-3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/5-3-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/5-3-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/09\/09\/comisiones-dictaminaron-sobre-la-modificacion-de-la-ley-sobre-uso-medicinal-del-cannabis-y-sus-derivados\/img_7061\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/IMG_7061-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/IMG_7061-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/IMG_7061-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ushuaia, mi\u00e9rcoles 9 de septiembre de 2020.- La Comisi\u00f3n de salud, minoridad y familia N\u00b0 5 se reuni\u00f3 por primera vez de manera remota. En agenda se encontraban siete asuntos de los cuales, la mayor\u00eda obtuvo dictamen favorable para ser tratado en la pr\u00f3xima sesi\u00f3n ordinaria. En tanto, asuntos como pedidos de informes sobre salud [&hellip;]<\/p>\n","protected":false},"author":352,"featured_media":21080,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[1971,445,1910,1970,1969,166,1968],"class_list":["post-21128","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa","tag-buenas-practicas-covid-19","tag-cannabis-medicinal","tag-endometriosis","tag-muerte-subita","tag-registro-provincial-de-historias-clinicas","tag-salud-mental","tag-seguro-de-salud-obligatorio"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/IMG_7061.jpg","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/21128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/352"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=21128"}],"version-history":[{"count":5,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/21128\/revisions"}],"predecessor-version":[{"id":21133,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/21128\/revisions\/21133"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media\/21080"}],"wp:attachment":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=21128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=21128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=21128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}