{"id":21166,"date":"2020-09-10T20:06:44","date_gmt":"2020-09-10T23:06:44","guid":{"rendered":"http:\/\/www.legistdf.gob.ar\/?p=21166"},"modified":"2020-09-10T20:06:44","modified_gmt":"2020-09-10T23:06:44","slug":"urquiza-la-presidenta-de-la-camara-resalto-el-trabajo-intenso-y-serio-para-modificar-el-reglamento-interno","status":"publish","type":"post","link":"https:\/\/www.legistdf.gob.ar\/index.php\/2020\/09\/10\/urquiza-la-presidenta-de-la-camara-resalto-el-trabajo-intenso-y-serio-para-modificar-el-reglamento-interno\/","title":{"rendered":"URQUIZA: La Presidenta de la C\u00e1mara resalt\u00f3 el trabajo \u201cintenso y serio\u201d para modificar el Reglamento Interno"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-21142 size-medium\" src=\"http:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/1-6-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/1-6-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/1-6-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/1-6-1024x683.jpg 1024w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/1-6-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/1-6.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/strong><strong>Ushuaia, jueves 10 de septiembre de 2020.- <\/strong><strong>Luego que el Parlamento aprobara la modificaci\u00f3n del Reglamento Interno para la incorporaci\u00f3n de tecnolog\u00eda al funcionamiento parlamentario \u2013sesiones presenciales, remotas o mixtas y\u00a0<\/strong><strong>firma digital-, la Presidenta de la C\u00e1mara afirm\u00f3 \u201cfue un trabajo muy intenso y serio por parte de todos los Legisladores\u201d.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.legistdf.gob.ar\/index.php\/2020\/09\/10\/legislatura-habilitaron-las-sesiones-presenciales-remotas-o-mixtas-y-la-firma-digital\/\" target=\"_blank\" rel=\"noopener noreferrer\">Las modificaciones se aplican a los art\u00edculos referidos al\u00a0qu\u00f3rum; sesiones donde se establece la metodolog\u00eda presencial, remota o mixta; integraci\u00f3n y reuniones; instalaci\u00f3n y elecci\u00f3n de autoridades; y firma digital.<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>\u201cDesde Presidencia y con el acompa\u00f1amiento de todo el personal de la C\u00e1mara, tenemos el desaf\u00edo de llevar adelante este nuevo funcionamiento\u201d asegur\u00f3 la\u00a0Presidenta del Poder Legislativo, y\u00a0record\u00f3 que estaba autorizada la participaci\u00f3n remota \u201cde los Legisladores de grupo de riesgo\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-21146 size-medium\" src=\"http:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/5-5-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/5-5-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/5-5-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/5-5-1024x683.jpg 1024w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/5-5-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/5-5.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Adelant\u00f3 que \u201clos encuentros legislativos de manera remota o mixta, ser\u00e1n aplicados s\u00f3lo en una situaci\u00f3n de emergencia y excepcional. La determinaci\u00f3n de ello, tiene que ser acordada y aprobada por todos los integrantes de la C\u00e1mara\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>La Presidenta de la C\u00e1mara indic\u00f3 que \u201cla adaptaci\u00f3n del Recinto de Sesiones y Comisiones se viene haciendo desde la primera sesi\u00f3n, de acuerdo a la coyuntura respecto de la pandemia que seguro va a continuar, muy probablemente, en el pr\u00f3ximo per\u00edodo\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Al finalizar, manifest\u00f3 que la pr\u00f3xima sesi\u00f3n legislativa, se dar\u00e1 en el marco que indica la modificaci\u00f3n del Reglamento Interno, que aprobaron hoy.<\/p>\n<p><iframe loading=\"lazy\" title=\"100920 URQUIZA: La Presidenta de la C\u00e1mara resalt\u00f3 el trabajo \u201cintenso y serio\u201d para modificar el RI\" width=\"844\" height=\"475\" src=\"https:\/\/www.youtube.com\/embed\/lrXU2lP37t8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<div class=\"fb-video\" data-allowfullscreen=\"true\" data-href=\"https:\/\/www.facebook.com\/874040226013478\/videos\/649760562411159\" style=\"background-color: #fff; display: inline-block;\"><\/div>\n<p style=\"text-align: right\"><em>AT<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ushuaia, jueves 10 de septiembre de 2020.- Luego que el Parlamento aprobara la modificaci\u00f3n del Reglamento Interno para la incorporaci\u00f3n de tecnolog\u00eda al funcionamiento parlamentario \u2013sesiones presenciales, remotas o mixtas y\u00a0firma digital-, la Presidenta de la C\u00e1mara afirm\u00f3 \u201cfue un trabajo muy intenso y serio por parte de todos los Legisladores\u201d. &nbsp; Las modificaciones se [&hellip;]<\/p>\n","protected":false},"author":352,"featured_media":21143,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[78,144,1966,117,79,87],"class_list":["post-21166","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa","tag-legislatura","tag-monica-urquiza","tag-reglamento-interno","tag-sesion","tag-tierra-del-fuego","tag-ushuaia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/09\/2-8.jpg","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/21166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/352"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=21166"}],"version-history":[{"count":1,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/21166\/revisions"}],"predecessor-version":[{"id":21167,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/21166\/revisions\/21167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media\/21143"}],"wp:attachment":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=21166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=21166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=21166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}