{"id":21820,"date":"2020-11-06T19:32:19","date_gmt":"2020-11-06T22:32:19","guid":{"rendered":"http:\/\/www.legistdf.gob.ar\/?p=21820"},"modified":"2020-11-06T19:32:19","modified_gmt":"2020-11-06T22:32:19","slug":"malvinas-a-200-anos-del-primer-izamiento-del-pabellon-nacional","status":"publish","type":"post","link":"https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/06\/malvinas-a-200-anos-del-primer-izamiento-del-pabellon-nacional\/","title":{"rendered":"MALVINAS: A 200 a\u00f1os del primer izamiento del Pabell\u00f3n nacional"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-21848 size-medium\" src=\"http:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7818-3-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7818-3-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7818-3-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7818-3-1024x683.jpg 1024w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7818-3-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7818-3.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Ushuaia, viernes 6 de noviembre de 2020.- La presidenta del Poder Legislativo, vicegobernadora M\u00f3nica Urquiza particip\u00f3 \u2013esta ma\u00f1ana- del acto en conmemoraci\u00f3n a los 200 a\u00f1os del primer izamiento del Pabell\u00f3n nacional en las Islas Malvinas. Tambi\u00e9n, acompa\u00f1aron el homenaje conmemorativo por el bicentenario, los legisladores Emmanuel Trentino (FORJA), Victoria Vuoto y Laura Colazo (PV). <\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>La ceremonia tuvo lugar en la plaza que recuerda y rinde homenaje a los ca\u00eddos en la guerra del Atl\u00e1ntico sur en 1982, sobre la avenida Maip\u00fa de la capital provincial y fue encabezado por gobernador Prof. Gustavo Melella. Adem\u00e1s, asistieron el intendente Walter Vuoto; Concejales; funcionarios provinciales, municipales y judiciales; combatientes de Malvinas, entre otros.<img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-21852 size-medium\" src=\"http:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7840-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7840-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7840-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7840-1024x683.jpg 1024w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7840-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7840.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>En horas del mediod\u00eda, la Presidenta del Parlamento fueguino acompa\u00f1\u00f3 al Gobernador en la Primera Reuni\u00f3n del Consejo Nacional de Asuntos Relativos a las Islas Malvinas, encabezada por el Presidente de la Naci\u00f3n, Dr. Alberto Fern\u00e1ndez.<\/p>\n<p>&nbsp;<\/p>\n<p>Por su parte, la leg\u00edtima Vicegobernadora de Malvinas en principio se refiri\u00f3 al acto que llev\u00f3 adelante en la plaza Malvinas y dijo que fue un momento \u201cmuy emocionante\u201d. En este sentido, Urquiza mencion\u00f3 las palabras de todas las autoridades y funcionarios del orden provincial, \u201cesto es una causa nacional y una pol\u00edtica de Estado, debemos seguir trabajando para la representaci\u00f3n de Malvinas\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Consultada sobre el momento hist\u00f3rico de la Legislatura con la nueva conformaci\u00f3n de Comisi\u00f3n 7, la Vicegobernadora sostuvo que \u201csiempre se trataron estos temas y se le dieron prioridad, pero se trataba en la Comisi\u00f3n de Legislaci\u00f3n (1). A partir de ahora tenemos este espacio de debate, donde se van a tratar todos estos temas\u201d, se\u00f1al\u00f3 Urquiza.<img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-21840 size-medium\" src=\"http:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7804-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7804-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7804-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7804-1024x683.jpg 1024w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7804-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7804.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Finalmente, la m\u00e1xima autoridad legislativa cit\u00f3 a la legisladora Laura Colazo y dijo que no solamente se tratar\u00e1n temas del archipi\u00e9lago, sino tambi\u00e9n los que tienen que ver con Ant\u00e1rtida. \u201cEs un sector muy importante de nuestra Provincia y como lo dijo Federico Greve, somos la Legislatura de nuestras Islas Malvinas o sea los 15 integrantes y yo\u201d, concluy\u00f3.<\/p>\n<p>&nbsp;<\/p>\n<p>Cabe se\u00f1alar que, en septiembre \u00faltimo, la Presidenta de la C\u00e1mara suscribi\u00f3 la resoluci\u00f3n de Presidencia N\u00b0 345\/2020, mediante la cual declar\u00f3 de inter\u00e9s provincial la iniciativa de la Asociaci\u00f3n de Periodistas de la Rep\u00fablica Argentina, quienes propiciaron la declaraci\u00f3n del d\u00eda 6 de noviembre de 2020 como \u00abD\u00eda Patrio\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>La propuesta se origin\u00f3 de acuerdo a la nota presentada por el Sr. Femando N\u00e9stor Ram\u00edrez, coordinador de la mencionada Asociaci\u00f3n, con motivo de celebrarse los 200 a\u00f1os del primer izamiento de la Bandera Argentina en las islas Malvinas lo que \u201cconstituy\u00f3 un acontecimiento hist\u00f3rico y muy caro a los sentimientos de nuestro pueblo\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>En los fundamentos de la resoluci\u00f3n, la titular del Poder Legislativo sostiene que \u201cla entidad, fundada el pasado 22 de junio y con casi 230 trabajadores y trabajadoras de prensa, tiene como uno de sus ejes la agenda Malvinas y en esa direcci\u00f3n promueve estas acciones celebratorias, para contribuir a un tema que une a todos los argentinos, sin bander\u00eda\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right\"><em>LVV-NEGM<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-21820 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/06\/malvinas-a-200-anos-del-primer-izamiento-del-pabellon-nacional\/img_7767\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7767-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7767-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7767-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/06\/malvinas-a-200-anos-del-primer-izamiento-del-pabellon-nacional\/img_7768\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7768-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7768-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7768-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/06\/malvinas-a-200-anos-del-primer-izamiento-del-pabellon-nacional\/img_7772-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7772-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7772-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7772-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/06\/malvinas-a-200-anos-del-primer-izamiento-del-pabellon-nacional\/img_7774-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7774-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7774-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7774-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/06\/malvinas-a-200-anos-del-primer-izamiento-del-pabellon-nacional\/img_7775\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7775-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7775-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7775-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/06\/malvinas-a-200-anos-del-primer-izamiento-del-pabellon-nacional\/img_7778-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7778-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7778-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7778-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/06\/malvinas-a-200-anos-del-primer-izamiento-del-pabellon-nacional\/img_7782-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7782-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7782-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7782-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/06\/malvinas-a-200-anos-del-primer-izamiento-del-pabellon-nacional\/img_7795-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7795-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7795-1-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7795-1-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/06\/malvinas-a-200-anos-del-primer-izamiento-del-pabellon-nacional\/img_7798-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7798-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7798-1-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7798-1-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/06\/malvinas-a-200-anos-del-primer-izamiento-del-pabellon-nacional\/img_7800\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7800-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7800-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7800-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/06\/malvinas-a-200-anos-del-primer-izamiento-del-pabellon-nacional\/img_7804-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7804-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7804-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7804-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/06\/malvinas-a-200-anos-del-primer-izamiento-del-pabellon-nacional\/img_7806-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7806-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7806-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7806-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/06\/malvinas-a-200-anos-del-primer-izamiento-del-pabellon-nacional\/img_7807\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7807-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7807-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7807-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/06\/malvinas-a-200-anos-del-primer-izamiento-del-pabellon-nacional\/img_7808-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7808-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7808-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7808-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/06\/malvinas-a-200-anos-del-primer-izamiento-del-pabellon-nacional\/img_7815\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7815-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7815-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7815-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/06\/malvinas-a-200-anos-del-primer-izamiento-del-pabellon-nacional\/img_7816-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7816-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7816-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7816-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/06\/malvinas-a-200-anos-del-primer-izamiento-del-pabellon-nacional\/img_7817-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7817-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7817-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7817-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/06\/malvinas-a-200-anos-del-primer-izamiento-del-pabellon-nacional\/img_7818\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7818-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7818-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7818-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/06\/malvinas-a-200-anos-del-primer-izamiento-del-pabellon-nacional\/img_7818-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7818-3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7818-3-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7818-3-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/06\/malvinas-a-200-anos-del-primer-izamiento-del-pabellon-nacional\/img_7824\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7824-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7824-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7824-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/06\/malvinas-a-200-anos-del-primer-izamiento-del-pabellon-nacional\/img_7831\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7831-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7831-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7831-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/06\/malvinas-a-200-anos-del-primer-izamiento-del-pabellon-nacional\/img_7833\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7833-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7833-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7833-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/06\/malvinas-a-200-anos-del-primer-izamiento-del-pabellon-nacional\/img_7840-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7840-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7840-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7840-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/06\/malvinas-a-200-anos-del-primer-izamiento-del-pabellon-nacional\/img_7842\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7842-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7842-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7842-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ushuaia, viernes 6 de noviembre de 2020.- La presidenta del Poder Legislativo, vicegobernadora M\u00f3nica Urquiza particip\u00f3 \u2013esta ma\u00f1ana- del acto en conmemoraci\u00f3n a los 200 a\u00f1os del primer izamiento del Pabell\u00f3n nacional en las Islas Malvinas. Tambi\u00e9n, acompa\u00f1aron el homenaje conmemorativo por el bicentenario, los legisladores Emmanuel Trentino (FORJA), Victoria Vuoto y Laura Colazo (PV). [&hellip;]<\/p>\n","protected":false},"author":352,"featured_media":21847,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[2034,1818,2037,1821,144,1822],"class_list":["post-21820","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa","tag-200-anos","tag-emmanuel-trentino","tag-izamiento-del-pabellon-nacional","tag-laura-colazo","tag-monica-urquiza","tag-victoria-vuoto"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7818.jpg","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/21820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/352"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=21820"}],"version-history":[{"count":1,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/21820\/revisions"}],"predecessor-version":[{"id":21855,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/21820\/revisions\/21855"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media\/21847"}],"wp:attachment":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=21820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=21820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=21820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}