{"id":22198,"date":"2020-11-29T18:45:22","date_gmt":"2020-11-29T21:45:22","guid":{"rendered":"http:\/\/www.legistdf.gob.ar\/?p=22198"},"modified":"2020-11-27T15:10:07","modified_gmt":"2020-11-27T18:10:07","slug":"comisiones-se-reunen-las-mesas-de-recursos-naturales-y-educacion","status":"publish","type":"post","link":"https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/29\/comisiones-se-reunen-las-mesas-de-recursos-naturales-y-educacion\/","title":{"rendered":"COMISIONES: Se re\u00fanen las mesas de Recursos Naturales y Educaci\u00f3n"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-22125 size-medium\" src=\"http:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_8205-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_8205-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_8205-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_8205-1024x683.jpg 1024w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_8205-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_8205.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Ushuaia, domingo 29 de noviembre.- La legisladora M\u00f3nica Acosta (FORJA), presidenta de la Comisi\u00f3n de Recursos Naturales (3), convoc\u00f3 un nuevo encuentro para el pr\u00f3ximo mi\u00e9rcoles 2 de diciembre a partir de las 11 h. All\u00ed los Parlamentarios analizar el <a href=\"http:\/\/www.legistdf.gob.ar\/lp\/novedadesip\/Asuntos%20Entrados%202019\/As.%20N%BA%20145-19.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">asunto 145\/19<\/a> que refiere a \u201cla prohibici\u00f3n en toda la jurisdicci\u00f3n provincial, la explotaci\u00f3n en criadero de especies salm\u00f3nidas\u201d, seg\u00fan se desprende del memorando interno N\u00b0 059\/20 de la Direcci\u00f3n de Comisiones. El encuentro se realizar\u00e1 en el recinto de sesiones bajo los protocolos sanitarios establecidos. <\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Cabe recordar, que en mayo del 2019 el bloque del Movimiento Popular Fueguino (MPF) present\u00f3 un proyecto que busca prohibir en toda la jurisdicci\u00f3n de Tierra del Fuego, Ant\u00e1rtida e Islas del Atl\u00e1ntico Sur, en \u00e1mbitos territoriales, lacustres o mar\u00edtimos, la instalaci\u00f3n de criaderos o establecimientos de procesamiento de especies ict\u00edcolas salm\u00f3nidas, bajo cualquier modalidad, como as\u00ed tambi\u00e9n toda explotaci\u00f3n industrial o comercial.<\/p>\n<p>&nbsp;<\/p>\n<p>En sus fundamentos, refiere que la sentencia de la C\u00e1mara de Apelaciones de Punta Arenas, Chile, caus\u00f3 en la sociedad fueguina \u201cgran conmoci\u00f3n\u201d, ya que, deja sin efecto una medida de no innovar oportunamente incoada y autorizada en primera instancia, aunque, \u201cvirtualmente habilit\u00f3 a la empresa Nova Austral S.A. de capitales noruegos, a cultivar alrededor de dos millones de salmones en cuatro jaulas a instalarse en las inmediaciones del canal Beagle, en la zona de Puerto Williams, a unos cinco kil\u00f3metros de la frontera trazada entre Argentina y Chile por imperio de los instrumentos internacionales vigentes entre las partes, en particular, el Tratado de L\u00edmites de 1881 y el Tratado de Paz y Amistad de 1984\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Cierto es que, \u201cel salm\u00f3n es una especie ajena al medio ecol\u00f3gico austral, cuya aparici\u00f3n causar\u00eda un desequilibrio dram\u00e1tico en el entorno marino, particularmente por la aptitud de generar enfermedades virales, parasitarias y bacterianas que no son propias de nuestras latitudes en virtud del enfoque industrial de criadero y su posterior procesamiento\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>En los fundamentos los Legisladores mopofistas expresaron que \u201ces necesario dar un paso m\u00e1s claro, profundo y contundente en t\u00e9rminos legales e institucionales a fin de impedir que en la jurisdicci\u00f3n provincial se instalen emprendimientos de estas caracter\u00edsticas\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-21710 size-medium\" src=\"http:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7697-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7697-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7697-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7697-1024x683.jpg 1024w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7697-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7697.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Adem\u00e1s, el presidente Comisi\u00f3n de Educaci\u00f3n (4), legislador Emmanuel Trentino (FORJA), cit\u00f3 para el mismo d\u00eda a las 14 horas a los integrantes de ese espacio de debate. En la reuni\u00f3n se espera contar con la presencia de representantes de los gremios de: Sindicato Unificado de Trabajadores de la Educaci\u00f3n Fueguina (SUTEF); Sindicato Argentino de Docentes Privados (SADOP); Uni\u00f3n Docentes Argentinos (UDA) y Asociaci\u00f3n de Maestros de Ense\u00f1anza T\u00e9cnica (AMET), seg\u00fan se desprende del memorando 058\/20.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right\"><em>MBCH-NEGM<\/em><\/p>\n<p style=\"text-align: right\"><em>Fotograf\u00edas de archivo<\/em><\/p>\n<p>&nbsp;<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-22198 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/20\/presupuesto-vialidad-provincial-y-la-federacion-de-bomberos-pasaron-por-la-legislatura\/img_8205\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_8205-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_8205-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_8205-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/11\/04\/comisiones-ministerio-de-gobierno-y-secretaria-de-malvinas-expusieron-su-presupuesto-2021\/img_7697\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7697-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7697-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/11\/IMG_7697-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2020\/10\/28\/comisiones-avanzan-en-el-proyecto-de-ley-que-regula-los-honorarios-de-los-abogados\/img_7494\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/10\/IMG_7494-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/10\/IMG_7494-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/10\/IMG_7494-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Ushuaia, domingo 29 de noviembre.- La legisladora M\u00f3nica Acosta (FORJA), presidenta de la Comisi\u00f3n de Recursos Naturales (3), convoc\u00f3 un nuevo encuentro para el pr\u00f3ximo mi\u00e9rcoles 2 de diciembre a partir de las 11 h. All\u00ed los Parlamentarios analizar el asunto 145\/19 que refiere a \u201cla prohibici\u00f3n en toda la jurisdicci\u00f3n provincial, la explotaci\u00f3n en [&hellip;]<\/p>\n","protected":false},"author":352,"featured_media":21560,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[80,1818,1817,799],"class_list":["post-22198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa","tag-educacion","tag-emmanuel-trentino","tag-monica-acosta","tag-recursos-naturales"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2020\/10\/IMG_7494.jpg","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/22198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/352"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=22198"}],"version-history":[{"count":1,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/22198\/revisions"}],"predecessor-version":[{"id":22199,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/22198\/revisions\/22199"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media\/21560"}],"wp:attachment":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=22198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=22198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=22198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}