{"id":2457,"date":"2017-06-06T12:02:26","date_gmt":"2017-06-06T15:02:26","guid":{"rendered":"http:\/\/www.legistdf.gob.ar\/?p=2457"},"modified":"2017-06-06T12:02:26","modified_gmt":"2017-06-06T15:02:26","slug":"legislatura-anuncian-nuevo-encuentro-de-la-comision-de-salud-publica","status":"publish","type":"post","link":"https:\/\/www.legistdf.gob.ar\/index.php\/2017\/06\/06\/legislatura-anuncian-nuevo-encuentro-de-la-comision-de-salud-publica\/","title":{"rendered":"LEGISLATURA: Anuncian nuevo encuentro de la Comisi\u00f3n de Salud P\u00fablica"},"content":{"rendered":"<p><strong>Ushuaia, martes 6 de junio de 2017.- Mediante memorando N&ordm; 049\/17, la presidenta de la Comisi&oacute;n de Salud P&uacute;blica (5), legisladora Liliana Mart&iacute;nez Allende (UCR &#8211; Cambiemos) cit&oacute; a los Legisladores integrantes de ese espacio de debate, a una reuni&oacute;n para el jueves 8 a las 15,30.<\/strong><\/p>\n<p>En la reuni&oacute;n, dar&aacute;n tratamiento a la situaci&oacute;n de los beneficiarios del Registro &Uacute;nico de Pensiones Especiales (RUPE) con la Obra Social de la Provincia de Tierra del Fuego (OSPTF). Para la ocasi&oacute;n, se invit&oacute; a la presidenta de la OSPTF, Margarita Gallardo y al secretario de Coordinaci&oacute;n de Pol&iacute;ticas para Personas con Discapacidad, Alejandro Rojo Vivot.<\/p>\n<pre><em>Con informaci&oacute;n de Prensa Legislativa\n\n<\/em><strong><a href=\"https:\/\/es-la.facebook.com\/PrensaLegislaturatdf\">\nFacebook<\/a> <a href=\"https:\/\/twitter.com\/PrensaLegisTDF\">Twitter<\/a> <a href=\"https:\/\/www.flickr.com\/photos\/prensalegistdf\/sets\/\">Flickr\n\n<\/a><\/strong>\n<strong>DIRECCI&Oacute;N DE PRENSA Y DIFUSI&Oacute;N INSTITUCIONAL LEGISLATURA DE TIERRA DEL FUEGO <\/strong><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Ushuaia, martes 6 de junio de 2017.- Mediante memorando N&ordm; 049\/17, la presidenta de la Comisi&oacute;n de Salud P&uacute;blica (5), legisladora Liliana Mart&iacute;nez Allende (UCR &#8211; Cambiemos) cit&oacute; a los Legisladores integrantes de ese espacio de debate, a una reuni&oacute;n para el jueves 8 a las 15,30. En la reuni&oacute;n, dar&aacute;n tratamiento a la situaci&oacute;n [&hellip;]<\/p>\n","protected":false},"author":352,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-2457","post","type-post","status-publish","format-standard","hentry","category-prensa"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/2457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/352"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=2457"}],"version-history":[{"count":0,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/2457\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=2457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=2457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=2457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}