{"id":31913,"date":"2022-04-04T16:41:07","date_gmt":"2022-04-04T19:41:07","guid":{"rendered":"https:\/\/www.legistdf.gob.ar\/?p=31913"},"modified":"2022-04-04T16:52:37","modified_gmt":"2022-04-04T19:52:37","slug":"osef-el-parlamento-analizara-iniciativas-de-modificacion-de-la-obra-social-provincial","status":"publish","type":"post","link":"https:\/\/www.legistdf.gob.ar\/index.php\/2022\/04\/04\/osef-el-parlamento-analizara-iniciativas-de-modificacion-de-la-obra-social-provincial\/","title":{"rendered":"OSEF: El Parlamento analizar\u00e1 iniciativas de modificaci\u00f3n de la obra social provincial"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-31914 size-medium\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/04\/photo5080531370538805306-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/04\/photo5080531370538805306-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/04\/photo5080531370538805306-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/04\/photo5080531370538805306-1024x682.jpg 1024w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/04\/photo5080531370538805306-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/04\/photo5080531370538805306.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Ushuaia, lunes de abril de 2022.- Los Presidentes de las Comisiones de Legislaci\u00f3n General N\u00b0 1, Presupuesto N\u00b0 2 y Salud P\u00fabica N\u00b0 5, convocaron a distintos encuentros a los Parlamentarios integrantes de esos espacios de an\u00e1lisis para este mi\u00e9rcoles y jueves. Abordar\u00e1n el asunto impulsado por el Ejecutivo provincial, que propone modificar la Ley N\u00ba 1071, de creaci\u00f3n de la Obra Social de la Provincia de Tierra del Fuego.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Los legisladores Federico Greve, Federico Sciurano y Daniel Rivarola, llamaron \u00a0a los Parlamentarios a una reuni\u00f3n conjunta en el sal\u00f3n de Comisiones del edificio de los bloques pol\u00edticos, para dar tratamiento a los asuntos <a href=\"https:\/\/www.legistdf.gob.ar\/lp\/novedadesip\/Asuntos%20Entrados%202022\/As.%20N%BA%20112-22.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">N\u00ba 112\/22<\/a> PEP Mensaje N\u00b0 05\/22, proyecto de Ley que modifica la <a href=\"http:\/\/200.41.191.125:134\/index.php\/1569-obra-social-de-la-provincia-de-tierra-del-fuego-osptf-creacion\" target=\"_blank\" rel=\"noopener noreferrer\">Ley provincial N\u00ba 1071<\/a> y N\u00ba <a href=\"https:\/\/www.legistdf.gob.ar\/lp\/novedadesip\/Asuntos%20Entrados%202021\/As.%20N%BA%20318-21.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">318\/21,<\/a> impulsado por distintos gremios provinciales y tomado por todos los bloques pol\u00edticos, sobre la Obra Social de los Empleados P\u00fablicos y Jubilados de la Provincia.<\/p>\n<p>&nbsp;<\/p>\n<p>Seg\u00fan el memorando N\u00ba 08\/22 de la Direcci\u00f3n de Comisiones, las reuniones se desarrollar\u00e1n el mi\u00e9rcoles 6 y jueves 7 de abril, en los horarios que a continuaci\u00f3n se detallan y con la participaci\u00f3n de los siguientes gremios:<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Mi\u00e9rcoles 6 de abril<\/strong><\/p>\n<p>10 h<\/p>\n<p>&#8211; Asociaci\u00f3n de Trabajadores del Estado (ATE &#8211; Ushuaia)<\/p>\n<p>&#8211; Asociaci\u00f3n de Trabajadores del Estado (ATE &#8211; Rio Grande)<\/p>\n<p>&nbsp;<\/p>\n<p>11 h<\/p>\n<p>&#8211; Sindicato Unificado de Trabajadores de la Educaci\u00f3n Fueguina (SUTEF)<\/p>\n<p>&#8211; Asociaci\u00f3n Sindical Obreros y Empleados Municipales (ASOEM R\u00edo Grande)<\/p>\n<p>&nbsp;<\/p>\n<p>12 h<\/p>\n<p>&#8211; Sindicato Obreros y Empleados Municipales (SOEM \u2013 Ushuaia)<\/p>\n<p>&#8211; Sindicato del Personal Jer\u00e1rquico (SPJ)<\/p>\n<p>&nbsp;<\/p>\n<p>15 h<\/p>\n<p>&#8211; Sindicato de Empleados Judiciales (SEJUP)<\/p>\n<p>&#8211; Sindicato de Luz y Fuerza<\/p>\n<p>16 h<\/p>\n<p>&#8211; Confederaci\u00f3n General del Trabajo (CGT)<\/p>\n<p>&#8211; Asociaci\u00f3n Bancaria<\/p>\n<p>&nbsp;<\/p>\n<p>17 h<\/p>\n<p>&#8211; Asociaci\u00f3n del Magisterio de Ense\u00f1anza T\u00e9cnica (AMET)<\/p>\n<p>&#8211; Asociaci\u00f3n del Personal Empleados Legislativos (APEL)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Jueves 7 de abril\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>10 h<\/p>\n<p>&#8211; OSEF y representante del Gobierno provincial<\/p>\n<p>&#8211; Asociaci\u00f3n de Jubilados<\/p>\n<p>&#8211; Beneficiarios RUPE<\/p>\n<p>&nbsp;<\/p>\n<p>12 h<\/p>\n<p>&#8211; Sindicato de Trabajadores de Obras Sanitarias (SITOS)<\/p>\n<p>&#8211; Asociaci\u00f3n de Trabajadores de la Sanidad Argentina (ATSA)<\/p>\n<p>&#8211; Uni\u00f3n del Personal Civil de la Naci\u00f3n (UPCN)<\/p>\n<p>&nbsp;<\/p>\n<p>13 h<\/p>\n<p>&#8211; Sindicato de Trabajadores Viales y Afines<\/p>\n<p>&#8211; Sindicato Argentino de M\u00fasicos (SADEM)<\/p>\n<p>&#8211; Asociaci\u00f3n Sindical de Empleados y Obreros Municipales (ASEOM)<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ushuaia, lunes de abril de 2022.- Los Presidentes de las Comisiones de Legislaci\u00f3n General N\u00b0 1, Presupuesto N\u00b0 2 y Salud P\u00fabica N\u00b0 5, convocaron a distintos encuentros a los Parlamentarios integrantes de esos espacios de an\u00e1lisis para este mi\u00e9rcoles y jueves. Abordar\u00e1n el asunto impulsado por el Ejecutivo provincial, que propone modificar la Ley [&hellip;]<\/p>\n","protected":false},"author":352,"featured_media":31914,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[84,85,78,119,179,2545,48],"class_list":["post-31913","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa","tag-comisiones","tag-legislacion-general","tag-legislatura","tag-ley","tag-osef","tag-presupeusto","tag-salud"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/04\/photo5080531370538805306.jpg","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/31913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/352"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=31913"}],"version-history":[{"count":2,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/31913\/revisions"}],"predecessor-version":[{"id":31917,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/31913\/revisions\/31917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media\/31914"}],"wp:attachment":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=31913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=31913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=31913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}