{"id":35418,"date":"2022-10-21T13:30:06","date_gmt":"2022-10-21T16:30:06","guid":{"rendered":"https:\/\/www.legistdf.gob.ar\/?p=35418"},"modified":"2022-10-21T13:30:06","modified_gmt":"2022-10-21T16:30:06","slug":"justicia-la-legisladora-monica-acosta-se-reunio-con-la-jueza-maria-del-carmen-battaini","status":"publish","type":"post","link":"https:\/\/www.legistdf.gob.ar\/index.php\/2022\/10\/21\/justicia-la-legisladora-monica-acosta-se-reunio-con-la-jueza-maria-del-carmen-battaini\/","title":{"rendered":"JUSTICIA: La legisladora M\u00f3nica Acosta se reuni\u00f3 con la jueza Mar\u00eda del Carmen Battaini"},"content":{"rendered":"<p><strong>Ushuaia, viernes 21 de octubre de 2022.- La legisladora M\u00f3nica Acosta (FORJA) se entrevist\u00f3 con la jueza del Superior Tribunal de Justicia Dra. Mar\u00eda del Carmen Battaini, con el fin de intercambiar ideas sobre distintos asuntos que se encuentran actualmente en la agenda legislativa. \u201cFue una reuni\u00f3n altamente positiva\u201d, sostuvo la referente del bloque FORJA.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Luego del encuentro, la Parlamentaria cont\u00f3 a Prensa Legislativa: \u201cMantuve una reuni\u00f3n con la integrante femenina de Superior Tribunal Dra. Mar\u00eda del Carmen Battaini. Fue una reuni\u00f3n en principio muy buena, muy amena, en virtud de que hab\u00eda una tem\u00e1tica en com\u00fan con distintos bloques legislativos, que radicaban en un proyecto como el de infancias, ni\u00f1os, ni\u00f1as y adolescentes, para incorporar o implementar la defensor\u00eda p\u00fablica en la Provincia\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>En ese sentido, Acosta plante\u00f3 la necesidad de conocer sobre \u201cel trabajo de campo, la cantidad de tiempo y de recursos humanos que requerir\u00edan, por parte de dicho Tribunal. Se expres\u00f3 \u201csorprendida\u201d por las perspectivas en el trabajo a futuro, no solamente por \u201cc\u00f3mo piensan trabajar el abordaje de las violencias, de ciertas experiencias en el resto del pa\u00eds que han dado buenos resultados\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Tambi\u00e9n, la legisladora M\u00f3nica Acosta hizo menci\u00f3n a \u201clo que se pretende tambi\u00e9n para algunos juzgados, como es el caso de Tolhuin, que si bien se ha inaugurado recientemente, la idea es trabajar fuertemente contra la violencia intrafamiliar y proteger a las ni\u00f1as, ni\u00f1os y adolescentes\u201d, afirm\u00f3 la Parlamentaria.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cPor otro lado, tambi\u00e9n estuvimos charlando sobre la posibilidad de intercambiar algunos proyectos, de los cuales queremos tener la opini\u00f3n de la magistrada, como es el caso de paridad\u201d, asegur\u00f3 la referente del bloque FORJA. Al respecto consider\u00f3 que es un \u201ctema de suma importancia, no solamente para las mujeres, sino para entablar pr\u00f3ximamente tambi\u00e9n el trabajo en las Comisiones\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Luego, se refiri\u00f3 al \u00faltimo de los temas abordados con la Jueza, \u201cun tema que para m\u00ed es de vital relevancia, en relaci\u00f3n a un proyecto que estoy impulsando, con el acompa\u00f1amiento de mis pares del bloque, de juicios por Jurados\u201d. Confirm\u00f3 que acordaron con la Dra. J\u00e9ssica Name, \u201csu asistente y colaboradora m\u00e1s cercana, de pasarle el proyecto para que ella pueda hacernos una devoluci\u00f3n, con algunas cuestiones tambi\u00e9n que ella considere apropiadas incorporar, cosa que tambi\u00e9n me pareci\u00f3 important\u00edsimo\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Se mostr\u00f3 abierta a recibir distintas opiniones sobre el tema, \u201cde ser necesario inclusive, si hay algunas cuestiones que pueden ser de disenso, tambi\u00e9n qued\u00f3 abierto el di\u00e1logo en ese sentido, como para poder tener una devoluci\u00f3n concreta. L\u00f3gicamente, lo considero como algo muy propicio, que instrumenta desde el llano, un nexo con la sociedad\u201d, consider\u00f3 respecto a este \u00faltimo proyecto. \u201cLa verdad que en t\u00e9rminos generales fue una muy buena reuni\u00f3n, altamente positiva\u201d, concluy\u00f3 la legisladora M\u00f3nica Acosta.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right\"><em>NEGM &#8211; LVV<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-35418 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2022\/10\/21\/justicia-la-legisladora-monica-acosta-se-reunio-con-la-jueza-maria-del-carmen-battaini\/img_3874\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_3874-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_3874-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_3874-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2022\/10\/21\/justicia-la-legisladora-monica-acosta-se-reunio-con-la-jueza-maria-del-carmen-battaini\/img_3879-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_3879-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_3879-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_3879-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2022\/10\/21\/justicia-la-legisladora-monica-acosta-se-reunio-con-la-jueza-maria-del-carmen-battaini\/img_3881-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_3881-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_3881-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_3881-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2022\/10\/21\/justicia-la-legisladora-monica-acosta-se-reunio-con-la-jueza-maria-del-carmen-battaini\/img_3883-4\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_3883-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_3883-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_3883-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2022\/10\/21\/justicia-la-legisladora-monica-acosta-se-reunio-con-la-jueza-maria-del-carmen-battaini\/img_3889-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_3889-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_3889-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_3889-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2022\/10\/21\/justicia-la-legisladora-monica-acosta-se-reunio-con-la-jueza-maria-del-carmen-battaini\/img_3890\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_3890-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_3890-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_3890-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2022\/10\/21\/justicia-la-legisladora-monica-acosta-se-reunio-con-la-jueza-maria-del-carmen-battaini\/img_3891\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_3891-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_3891-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_3891-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Ushuaia, viernes 21 de octubre de 2022.- La legisladora M\u00f3nica Acosta (FORJA) se entrevist\u00f3 con la jueza del Superior Tribunal de Justicia Dra. Mar\u00eda del Carmen Battaini, con el fin de intercambiar ideas sobre distintos asuntos que se encuentran actualmente en la agenda legislativa. \u201cFue una reuni\u00f3n altamente positiva\u201d, sostuvo la referente del bloque FORJA. [&hellip;]<\/p>\n","protected":false},"author":352,"featured_media":35419,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[130,1636,1817,1954,1267],"class_list":["post-35418","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa","tag-legislaturatdf","tag-maria-del-carmen-battaini","tag-monica-acosta","tag-poder-judicial","tag-superior-tribunal-de-justicia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_3874.jpg","_links":{"self":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/35418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/352"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=35418"}],"version-history":[{"count":2,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/35418\/revisions"}],"predecessor-version":[{"id":35441,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/35418\/revisions\/35441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media\/35419"}],"wp:attachment":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=35418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=35418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=35418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}