{"id":35443,"date":"2022-10-21T14:24:00","date_gmt":"2022-10-21T17:24:00","guid":{"rendered":"https:\/\/www.legistdf.gob.ar\/?p=35443"},"modified":"2022-10-21T14:27:35","modified_gmt":"2022-10-21T17:27:35","slug":"educacion-tierra-del-fuego-celebro-el-centenario-de-la-escuela-n-2-de-rio-grande","status":"publish","type":"post","link":"https:\/\/www.legistdf.gob.ar\/index.php\/2022\/10\/21\/educacion-tierra-del-fuego-celebro-el-centenario-de-la-escuela-n-2-de-rio-grande\/","title":{"rendered":"EDUCACI\u00d3N: Tierra del Fuego celebr\u00f3 el centenario de la Escuela N\u00b0 2 de R\u00edo Grande"},"content":{"rendered":"<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 14pt\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-35449 size-medium\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9883-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9883-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9883-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9883-1024x683.jpg 1024w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9883-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9883.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>R\u00edo Grande, viernes 21 de octubre de 2022.- Con los caracter\u00edsticos vientos patag\u00f3nicos de primavera, R\u00edo Grande y la Provincia conmemoraron hoy el centenario de la Escuela N\u00b0 2, Dr. Benjam\u00edn Zorrilla. Con la participaci\u00f3n de la comunidad educativa; las familias, estudiantes, exdocentes y exalumnos, las autoridades fueguinas acompa\u00f1aron el hito riograndense que se inscribe en las celebraciones por los 100 a\u00f1os de la Ciudad norte. Tambi\u00e9n, reinauguraron la Campana por la Paz y el Bien que hab\u00eda instalado la gesti\u00f3n del exintendente Colazo en la esquina de Belgrano y San Mart\u00edn.<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\">El acto inici\u00f3 pasadas las 9 de hoy y continu\u00f3 hasta el mediod\u00eda, con la reinauguraci\u00f3n de la Campana por la Paz y el Bien, que se ubica en la esquina de las avenidas Belgrano y San Mart\u00edn.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 14pt\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-35451 size-medium alignright\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9831-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9831-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9831-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9831-1024x683.jpg 1024w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9831-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9831.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Consultada por Prensa Legislativa, Rolando Barros celebr\u00f3 que \u201clos nenes y las nenas lo disfrutaron, sali\u00f3 todo hermoso\u201d dijo este mediod\u00eda luego que, entre los presentes que recibi\u00f3 la instituci\u00f3n, las y los estudiantes junto a sus docentes, recrearon el paso de los 100 a\u00f1os de la Escuela 2, junto al crecimiento de la sociedad riograndense y el devenir de la historia argentina.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\">La directora de la escuela, dijo que se trata de un centenario donde la comunidad educativa \u201cfue cambiando, creciendo, avanzando y mejorando hasta llegar a ser una escuela centenaria\u201d. Entendi\u00f3 que entre sus pasillos, convivieron ni\u00f1os \u201cque al crecer y convertirse en padres, trajeron a sus hijos y luego a sus nietos\u201d. Hoy, la 2\u00a0 alberga a \u201cm\u00e1s de 405 alumnos, \u00e1vidos de recibir conocimientos y alcanzar una formaci\u00f3n integral para su vida futura\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 14pt\">La docente resalt\u00f3 que la instituci\u00f3n \u201ctiene un equipo de excelencia, que desempe\u00f1a su trabajo con compromiso, esmero, dedicaci\u00f3n, dando d\u00eda a d\u00eda, lo mejor de s\u00ed\u201d. En su alocuci\u00f3n, Rolando Barros resalt\u00f3 al equipo no docente de porter\u00eda y cocina; al personal del gabinete psicopedag\u00f3gico; y donde las familias \u201cest\u00e1n presentes acompa\u00f1ando a sus hijos\u201d. Al finalizar, dijo que se trata de \u201cun honor\u201d ser la directora de la Escuela N\u00b0 2, espacio donde ponder\u00f3 el trabajo del equipo de conducci\u00f3n enfocado en el \u201crespeto, la humildad, la tolerancia y la sensibilidad\u201d, cerr\u00f3.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-35452 size-medium\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9865-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9865-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9865-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9865-1024x683.jpg 1024w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9865-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9865.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>A continuaci\u00f3n, las y los estudiantes de los diversos niveles de aprendizaje, recrearon hitos de nuestra cultura como la inmigraci\u00f3n yugoeslava y chilena con sus danzas; el folclore argentino; el tango y demostraciones de destrezas deportivas. P\u00e1rrafo aparte, cabe se\u00f1alar el recordatorio que hicieron sobre la \u00faltima dictadura c\u00edvico militar; el mundial de 1978 y cerraron con el saludo de las y los egresados de la promoci\u00f3n centenaria de esa escuela riograndense. Momento que dio lugar a la emoci\u00f3n y las l\u00e1grimas por parte de esa comunidad educativa.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\">Al finalizar la conmemoraci\u00f3n, se trasladaron al exterior del edificio y en la esquina de las avenidas Belgrano y San Mart\u00edn, reinauguraron la Campana por la Paz y el Bien que hab\u00eda instalado la gesti\u00f3n del exintendente y actual legislador del Partido Verde, Jorge Colazo.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-35450 size-medium\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9936-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9936-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9936-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9936-1024x683.jpg 1024w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9936-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9936.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Participaron de la celebraci\u00f3n, las legisladoras Mar\u00eda Laura Colazo (PV), Myriam Mart\u00ednez y Andrea Freites (FdT-PJ) junto al Vicepresidente 1\u00b0 de la C\u00e1mara legislativa, legislador Dami\u00e1n L\u00f6ffler (MPF); y los legisladores Federico Greve (FORJA) y Jorge Colazo (PV). Presencia de Veteranos de Guerra de Malvinas; del intendente de la Ciudad, Mart\u00edn P\u00e9rez y representantes del Concejo Deliberante, fuerzas vivas y comunidad riograndense.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right\"><em>AT<\/em><\/p>\n<p style=\"text-align: right\"><a href=\"https:\/\/drive.google.com\/drive\/folders\/1a-gObzaZs_ezc65NkCmFFdv-uCghTNw3?usp=sharing\" target=\"_blank\" rel=\"noopener noreferrer\"><em>Galer\u00eda de im\u00e1genes<\/em><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-35443 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2022\/10\/21\/educacion-tierra-del-fuego-celebro-el-centenario-de-la-escuela-n-2-de-rio-grande\/img_9788-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9788-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9788-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9788-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2022\/10\/21\/educacion-tierra-del-fuego-celebro-el-centenario-de-la-escuela-n-2-de-rio-grande\/img_9783-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9783-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9783-1-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9783-1-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2022\/10\/21\/educacion-tierra-del-fuego-celebro-el-centenario-de-la-escuela-n-2-de-rio-grande\/img_9791\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9791-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9791-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9791-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2022\/10\/21\/educacion-tierra-del-fuego-celebro-el-centenario-de-la-escuela-n-2-de-rio-grande\/img_9792-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9792-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9792-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9792-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2022\/10\/21\/educacion-tierra-del-fuego-celebro-el-centenario-de-la-escuela-n-2-de-rio-grande\/img_9883-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9883-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9883-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9883-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2022\/10\/21\/educacion-tierra-del-fuego-celebro-el-centenario-de-la-escuela-n-2-de-rio-grande\/img_9936-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9936-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9936-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9936-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2022\/10\/21\/educacion-tierra-del-fuego-celebro-el-centenario-de-la-escuela-n-2-de-rio-grande\/img_9831-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9831-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9831-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9831-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2022\/10\/21\/educacion-tierra-del-fuego-celebro-el-centenario-de-la-escuela-n-2-de-rio-grande\/img_9865-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9865-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9865-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9865-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>R\u00edo Grande, viernes 21 de octubre de 2022.- Con los caracter\u00edsticos vientos patag\u00f3nicos de primavera, R\u00edo Grande y la Provincia conmemoraron hoy el centenario de la Escuela N\u00b0 2, Dr. Benjam\u00edn Zorrilla. Con la participaci\u00f3n de la comunidad educativa; las familias, estudiantes, exdocentes y exalumnos, las autoridades fueguinas acompa\u00f1aron el hito riograndense que se inscribe [&hellip;]<\/p>\n","protected":false},"author":352,"featured_media":35452,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[2272,80,2721,2722,144,96,79],"class_list":["post-35443","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa","tag-centenario","tag-educacion","tag-escuela-2","tag-mariana-rolando-barros","tag-monica-urquiza","tag-rio-grande","tag-tierra-del-fuego"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_9865.jpg","_links":{"self":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/35443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/352"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=35443"}],"version-history":[{"count":2,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/35443\/revisions"}],"predecessor-version":[{"id":35454,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/35443\/revisions\/35454"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media\/35452"}],"wp:attachment":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=35443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=35443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=35443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}