{"id":35829,"date":"2022-11-07T19:12:01","date_gmt":"2022-11-07T22:12:01","guid":{"rendered":"https:\/\/www.legistdf.gob.ar\/?p=35829"},"modified":"2022-11-07T19:12:01","modified_gmt":"2022-11-07T22:12:01","slug":"trentino-el-parlamento-patagonico-logro-ser-visible-en-la-region-y-el-pais","status":"publish","type":"post","link":"https:\/\/www.legistdf.gob.ar\/index.php\/2022\/11\/07\/trentino-el-parlamento-patagonico-logro-ser-visible-en-la-region-y-el-pais\/","title":{"rendered":"TRENTINO: El Parlamento Patag\u00f3nico logr\u00f3 ser visible en la regi\u00f3n y el pa\u00eds"},"content":{"rendered":"<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 14pt\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-35299 size-medium\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_0036-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_0036-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_0036-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_0036-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/10\/IMG_0036.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Ushuaia, lunes 7 de noviembre de 2022.- El presidente del Parlamento Patag\u00f3nico, legislador Emmanuel Trentino, resalt\u00f3 \u201cel gran trabajo\u201d que llev\u00f3 adelante la gesti\u00f3n que pronto, dejar\u00e1 de guiar ese Cuerpo colegiado. <a href=\"https:\/\/www.legistdf.gob.ar\/index.php\/2022\/11\/07\/legislatura-finaliza-la-gestion-de-tierra-del-fuego-al-frente-del-parlamento-patagonico\/\" target=\"_blank\" rel=\"noopener noreferrer\">Tierra del Fuego, encabezar\u00e1 la cuarta sesi\u00f3n legislativa este mi\u00e9rcoles 9<\/a>, y al d\u00eda siguiente, en un acto protocolar, har\u00e1 entrega del mandato a Santa Cruz, ser\u00e1 en un momento \u201chist\u00f3rico\u201d, en la base ant\u00e1rtica vicecomodoro Marambio.<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\">En di\u00e1logo con Prensa Legislativa, Trentino calific\u00f3 como \u201cel gran trabajo\u201d que signific\u00f3 volver a poner al Parlamento Patag\u00f3nico, en el centro de la atenci\u00f3n de las provincias que la componen y de la Naci\u00f3n misma. En este sentido, record\u00f3 que en los \u201ccasi tres a\u00f1os de gesti\u00f3n\u201d, se aplicaron modificaciones sustanciales al Reglamento Interno debido a la contingencia que plante\u00f3 la pandemia por COVID-19. En este punto, record\u00f3 tambi\u00e9n que se cre\u00f3 un manual de procedimiento administrativo, para la gesti\u00f3n de los asuntos legislativos.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\">El Legislador, se\u00f1al\u00f3 que \u201cm\u00e1s all\u00e1 de celebrar la cuarta sesi\u00f3n ordinaria de 2022\u201d en la capital fueguina, el encuentro ser\u00e1 un \u201cmomento hist\u00f3rico y \u00fanico\u201d ya que el traspaso de mando se concretar\u00e1 en la base Marambio de la Ant\u00e1rtida Argentina, donde se elaborar\u00e1 una declaraci\u00f3n del Parlamento Patag\u00f3nico en el continente blanco.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-35830 size-medium\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/11\/IMG_2468-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/11\/IMG_2468-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/11\/IMG_2468-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/11\/IMG_2468-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/11\/IMG_2468.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\u201cEste Parlamento, -record\u00f3- desde siempre trabaja las cuestiones de soberan\u00eda\u201d y ejemplific\u00f3 con la Causa Malvinas, \u201cmuy arraigada\u201d en las diversas gestiones del Cuerpo. Las expectativas \u201cson muchas\u201d, de cara a la \u00faltima sesi\u00f3n con Tierra del Fuego al frente del \u00faltimo encuentro del a\u00f1o.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 14pt\">Trentino resalt\u00f3, a pocas horas de la \u00faltima sesi\u00f3n que lo tendr\u00e1 como Presidente, \u201cla sensaci\u00f3n del deber cumplido, no en mi persona\u201d y lo extendi\u00f3 al resto de la Composici\u00f3n legislativa que integr\u00f3 la conducci\u00f3n del Parlamento. Entonces, salud\u00f3 a su par, legisladora M\u00f3nica Acosta en la vicepresidencia y Federico Greve, en la secretar\u00eda. Tambi\u00e9n, destac\u00f3 la impronta que imprimieron al Parlamento Patag\u00f3nico \u201clos Presidentes de las Comisiones, que confiaron en m\u00ed, para llevar adelante esta gesti\u00f3n\u201d, salud\u00f3.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\">En este sentido, puso en relieve el trabajo de las \u00e1reas involucradas en la concreci\u00f3n de cada encuentro, y saludo al personal de planta permanente y planta pol\u00edtica, \u201cque me apoyaron y acompa\u00f1aron en las siete sesiones, para hacer historia\u201d, valor\u00f3 esta tarde.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-35831 size-medium\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/11\/IMG_2719-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/11\/IMG_2719-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/11\/IMG_2719-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/11\/IMG_2719-1024x683.jpg 1024w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/11\/IMG_2719-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/11\/IMG_2719.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>El Legislador dijo que el Parlamento Patag\u00f3nico fue de \u201cmenos a m\u00e1s\u201d y en la actualidad, la Regi\u00f3n de la Patagonia goza de visibilidad, en funci\u00f3n del trabajo que dieron las seis provincias que la componen, \u201cen la escena nacional\u201d. En este sentido, opin\u00f3 que se trata de un trabajo de intercambio legislativo que involucr\u00f3 a todos los sectores, en pos de dar cuenta de la realidad de las vecinos y vecinos del extremo sur de Argentina.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\">Finalmente, consultado sobre el derrotero que imprimi\u00f3 el Cuerpo en los \u00faltimos a\u00f1os, el referente de FORJA en la Legislatura fueguina se\u00f1al\u00f3 que \u201chemos dejado la vara bien alta\u201d y no dudo en afirmar que, tanto las y los diputados santacruce\u00f1os, como el personal t\u00e9cnico de la Legislatura de Santa Cruz, \u201cestar\u00e1n a la altura de las circunstancias\u201d, debido a su compromiso ya demostrado oportunamente, cerr\u00f3.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right\"><em>AT-Archivo<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ushuaia, lunes 7 de noviembre de 2022.- El presidente del Parlamento Patag\u00f3nico, legislador Emmanuel Trentino, resalt\u00f3 \u201cel gran trabajo\u201d que llev\u00f3 adelante la gesti\u00f3n que pronto, dejar\u00e1 de guiar ese Cuerpo colegiado. Tierra del Fuego, encabezar\u00e1 la cuarta sesi\u00f3n legislativa este mi\u00e9rcoles 9, y al d\u00eda siguiente, en un acto protocolar, har\u00e1 entrega del mandato [&hellip;]<\/p>\n","protected":false},"author":352,"featured_media":35831,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[1818,2740,1980,117,79,87],"class_list":["post-35829","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa","tag-emmanuel-trentino","tag-marambio","tag-parlamento-patagonico","tag-sesion","tag-tierra-del-fuego","tag-ushuaia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/11\/IMG_2719.jpg","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/35829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/352"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=35829"}],"version-history":[{"count":2,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/35829\/revisions"}],"predecessor-version":[{"id":35833,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/35829\/revisions\/35833"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media\/35831"}],"wp:attachment":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=35829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=35829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=35829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}