{"id":35836,"date":"2022-11-08T11:25:27","date_gmt":"2022-11-08T14:25:27","guid":{"rendered":"https:\/\/www.legistdf.gob.ar\/?p=35836"},"modified":"2022-11-08T11:25:27","modified_gmt":"2022-11-08T14:25:27","slug":"comisiones-por-peninsula-mitre-hoy-se-reuniran-legislacion-general-y-ambiente","status":"publish","type":"post","link":"https:\/\/www.legistdf.gob.ar\/index.php\/2022\/11\/08\/comisiones-por-peninsula-mitre-hoy-se-reuniran-legislacion-general-y-ambiente\/","title":{"rendered":"COMISIONES: Por Pen\u00ednsula Mitre hoy se reunir\u00e1n Legislaci\u00f3n General y Ambiente"},"content":{"rendered":"<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 14pt\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-35837 size-medium\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/11\/IMG_20221104_170103373-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/11\/IMG_20221104_170103373-300x169.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/11\/IMG_20221104_170103373-768x432.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/11\/IMG_20221104_170103373-1024x576.jpg 1024w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/11\/IMG_20221104_170103373-160x90.jpg 160w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Ushuaia, martes 8 de noviembre de 2022.- Luego del dictamen en mayor\u00eda alcanzado en la Comisi\u00f3n de Recursos Naturales N\u00b0 3, cabecera del asunto sobre la creaci\u00f3n del \u00c1rea Natural Protegida de Pen\u00ednsula Mitre, la Legislatura volver\u00e1 a reunirse hoy, para abordar la iniciativa del FdT-PJ y PV, se trata del asunto N\u00b0 614\/21. Las Comisiones N\u00b0 4 y N\u00b0 1, se reunir\u00e1n esta tarde desde las 15,30 h en busca de alcanzar mismo tr\u00e1mite parlamentario. <\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\">Todo indica que el dictamen favorable en ambos espacios, posibilita que el asunto est\u00e9 en condiciones de ir al Recinto de Sesiones cuando las y los Legisladores acuerden el llamado a una sesi\u00f3n y sancionarlo. M\u00f3nica Acosta (FORJA), titular de la Comisi\u00f3n N\u00b0 3, hab\u00eda dicho a Prensa Legislativa que, luego de m\u00e1s de tres d\u00e9cadas, la Provincia est\u00e1 cercana de alcanzar la protecci\u00f3n de la porci\u00f3n sudoriental de la Isla Grande.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\">Esa normativa ser\u00e1 un hecho significativo e hist\u00f3rico, que tras el Decreto provincial N\u00b0 1710\/20 de protecci\u00f3n del \u00e1rea por parte del Ejecutivo fueguino, buscar\u00e1 las voluntades para los dict\u00e1menes en las comisiones que presiden Emmanuel Trentino y Federico Greve.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\">Asi, Acosta anticip\u00f3 que luego de lograr los dict\u00e1menes necesarios, el llamado a una sesi\u00f3n especial, ser\u00e1 el siguiente paso y asi, dotar a las y los fueguinos de una Ley provincial que proteja Pen\u00ednsula Mitre.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right\"><em>AT<\/em><\/p>\n<p>&nbsp;<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"gwogDK8i9H\"><p><a href=\"https:\/\/www.legistdf.gob.ar\/index.php\/2022\/11\/04\/35776\/\">AMBIENTE: Dictaminaron en mayor\u00eda por la protecci\u00f3n de Pen\u00ednsula Mitre<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#171;AMBIENTE: Dictaminaron en mayor\u00eda por la protecci\u00f3n de Pen\u00ednsula Mitre&#187; &#8212; Legislatura TDF A.I.A.S.\" src=\"https:\/\/www.legistdf.gob.ar\/index.php\/2022\/11\/04\/35776\/embed\/#?secret=gwogDK8i9H\" data-secret=\"gwogDK8i9H\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ushuaia, martes 8 de noviembre de 2022.- Luego del dictamen en mayor\u00eda alcanzado en la Comisi\u00f3n de Recursos Naturales N\u00b0 3, cabecera del asunto sobre la creaci\u00f3n del \u00c1rea Natural Protegida de Pen\u00ednsula Mitre, la Legislatura volver\u00e1 a reunirse hoy, para abordar la iniciativa del FdT-PJ y PV, se trata del asunto N\u00b0 614\/21. Las [&hellip;]<\/p>\n","protected":false},"author":352,"featured_media":35837,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-35836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2022\/11\/IMG_20221104_170103373.jpg","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/35836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/352"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=35836"}],"version-history":[{"count":1,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/35836\/revisions"}],"predecessor-version":[{"id":35838,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/35836\/revisions\/35838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media\/35837"}],"wp:attachment":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=35836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=35836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=35836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}