{"id":37531,"date":"2023-04-02T19:35:47","date_gmt":"2023-04-02T22:35:47","guid":{"rendered":"https:\/\/www.legistdf.gob.ar\/?p=37531"},"modified":"2023-04-02T19:35:47","modified_gmt":"2023-04-02T22:35:47","slug":"vigilia-rio-grande-vivio-la-29-medianoche-malvinera-con-la-soberania-como-bandera","status":"publish","type":"post","link":"https:\/\/www.legistdf.gob.ar\/index.php\/2023\/04\/02\/vigilia-rio-grande-vivio-la-29-medianoche-malvinera-con-la-soberania-como-bandera\/","title":{"rendered":"VIGILIA: R\u00edo Grande vivi\u00f3 la 29\u00b0 medianoche malvinera, con la soberan\u00eda como bandera"},"content":{"rendered":"<p><span style=\"font-size: 14pt\"><strong><span style=\"font-family: arial, helvetica, sans-serif\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-37534 size-medium\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v3-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v3-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v3-768x513.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v3-1024x684.jpg 1024w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v3-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v3.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>R\u00edo Grande, domingo 2 de abril de 2023.- En la Capital Nacional de la Vigilia por la gloriosa Gesta de Malvinas, R\u00edo Grande, las m\u00e1ximas autoridades fueguinas asistieron a la tradicional reuni\u00f3n entre las familias y excombatientes, que se conmemora desde hace 29 a\u00f1os. Encabezado por los Veteranos y Veteranas de Guerra, el acto inici\u00f3 minutos antes de la medianoche del domingo. M\u00f3nica Urquiza junto a las legisladoras Myriam Mart\u00ednez y Andrea Freites (FdT-PJ); Liliana Mart\u00ednez Allende (UCR) y Mar\u00eda Laura Colazo (PV), junto a los legisladores Federico Sciurano (UCR) y Federico Greve y Emmanuel Trentino (FORJA) acompa\u00f1aron, en representaci\u00f3n de la Legislatura provincial.<\/span><\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\">El viento poco a poco hizo notar su presencia, mientras las familias de la ciudad, iniciaron la Vigilia con diversos n\u00fameros art\u00edsticos en honor a la Gesta de 1982, hasta que la hist\u00f3rica vos de la Vigilia, locutor Miguel V\u00e1zquez, anunci\u00f3 los minutos restantes para llegar a la medianoche del 2 de abril.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-37536 size-medium\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v5-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v5-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v5-768x513.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v5-1024x684.jpg 1024w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v5-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v5.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>En la oportunidad, VGM Sergio Marroco, enumer\u00f3 distintas cuestiones que hacen a la historia de los 41 a\u00f1os de reclamos que mantienen los excombatientes de Malvinas. Asi, record\u00f3 \u201clos diversos anuncios y promesas que fueron realizados\u201d en oportunidad del 40 aniversario, en 2022, y sostuvo que \u201calgunas fueron cumplidas, otras en proceso de concretarse y algunas, en el olvido\u201d. Enumer\u00f3 esos reclamos, \u201csin \u00e1nimos de interpelaci\u00f3n alguna\u201d, ante las autoridades fueguinas, Legisladores nacionales y provinciales; concejales; referentes de las fuerzas vivas y las Veteranos y los Veteranos de Guerra, que se ubicaron al frente de la comunidad riograndense, en el monumento principal frente a la costa del Mar Argentino.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\">Marroco continu\u00f3 con su alocuci\u00f3n, frente a las autoridades nacionales, encabezadas por el titular de la cartera de Defensa de la Naci\u00f3n, ministro Jorge Taiana, y pidi\u00f3 el reconocimiento de la Comisi\u00f3n Nacional de Veteranos de Guerra, para que la entidad, \u201cpueda hacer su trabajo en beneficio de todos los Veteranos de Guerra del pa\u00eds\u201d. Dijo que en la actualidad, esa acci\u00f3n se desarrolla de manera personal. Tambi\u00e9n alz\u00f3 su vos respecto de las mejoras en las prestaciones sanitarias y previsionales hacia los excombatientes.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\">Tambi\u00e9n se\u00f1al\u00f3 que desde las organizaciones que los agrupan, \u201chemos tenido di\u00e1logo con los Gobiernos de turno\u201d y destac\u00f3 al Ejecutivo provincial al calificarlo \u201camable, cordial y frontal\u201d, relaci\u00f3n en las que pueden \u201cdiscutir, disentir y acordar\u201d. En otro p\u00e1rrafo, dijo que \u201cfue emocionante\u201d la decisi\u00f3n de la Legislatura fueguina al \u201cdeclarar inaplicable para nuestra Provincia, los acuerdos de Madrid\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-37532 size-medium\" style=\"font-family: arial, helvetica, sans-serif;font-size: 16px\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v1-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v1-768x513.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v1-1024x684.jpg 1024w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v1-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v1.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\">La presencia legislativa, encabezada por la Presidenta de la C\u00e1mara, vicegobernadora M\u00f3nica Urquiza, fue desde la misa de campa\u00f1a celebrada horas antes, de forma constante en inmediaciones del Parque del Centenario de R\u00edo Grande. Las miradas pol\u00edticas de la Legislatura, acompa\u00f1aron a cada Veterana y cada Veterano, como sucede desde la institucionalizaci\u00f3n de este encuentro, en la costanera de la Ciudad hace ya 29 a\u00f1os.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right\"><em>AH-AT<\/em><\/p>\n<p style=\"text-align: right\"><a href=\"https:\/\/drive.google.com\/drive\/folders\/1k_pj611RMUzHJQyEf0t5rbeaDBa0cVBA?usp=share_link\" target=\"_blank\" rel=\"noopener noreferrer\">Galer\u00eda de im\u00e1genes<\/a><\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 25%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-37531 gallery-columns-4 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2023\/04\/02\/vigilia-rio-grande-vivio-la-29-medianoche-malvinera-con-la-soberania-como-bandera\/v1\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v1-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v1-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2023\/04\/02\/vigilia-rio-grande-vivio-la-29-medianoche-malvinera-con-la-soberania-como-bandera\/v2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v2-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v2-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2023\/04\/02\/vigilia-rio-grande-vivio-la-29-medianoche-malvinera-con-la-soberania-como-bandera\/v3\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v3-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v3-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2023\/04\/02\/vigilia-rio-grande-vivio-la-29-medianoche-malvinera-con-la-soberania-como-bandera\/v5\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v5-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v5-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v5-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>R\u00edo Grande, domingo 2 de abril de 2023.- En la Capital Nacional de la Vigilia por la gloriosa Gesta de Malvinas, R\u00edo Grande, las m\u00e1ximas autoridades fueguinas asistieron a la tradicional reuni\u00f3n entre las familias y excombatientes, que se conmemora desde hace 29 a\u00f1os. Encabezado por los Veteranos y Veteranas de Guerra, el acto inici\u00f3 [&hellip;]<\/p>\n","protected":false},"author":352,"featured_media":37534,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[2894,78,141,96,79,2542],"class_list":["post-37531","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa","tag-2-de-abril","tag-legislatura","tag-malvinas","tag-rio-grande","tag-tierra-del-fuego","tag-vigilia-por-malvinas"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/04\/v3.jpg","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/37531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/352"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=37531"}],"version-history":[{"count":1,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/37531\/revisions"}],"predecessor-version":[{"id":37537,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/37531\/revisions\/37537"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media\/37534"}],"wp:attachment":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=37531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=37531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=37531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}