{"id":41910,"date":"2024-03-06T10:43:48","date_gmt":"2024-03-06T13:43:48","guid":{"rendered":"https:\/\/www.legistdf.gob.ar\/?p=41910"},"modified":"2024-03-06T10:43:48","modified_gmt":"2024-03-06T13:43:48","slug":"salud-proponen-abordaje-a-la-salud-mental-de-las-adolescencias-fueguinas","status":"publish","type":"post","link":"https:\/\/www.legistdf.gob.ar\/index.php\/2024\/03\/06\/salud-proponen-abordaje-a-la-salud-mental-de-las-adolescencias-fueguinas\/","title":{"rendered":"SALUD: Proponen abordaje a la salud mental de las adolescencias fueguinas"},"content":{"rendered":"<p><span style=\"font-size: 14pt\"><strong><span style=\"font-family: arial, helvetica, sans-serif\"><a href=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/09\/IMG_8477-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-39713 size-medium\" title=\"Parlamento Juvenil 2023\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/09\/IMG_8477-1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/09\/IMG_8477-1-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/09\/IMG_8477-1-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/09\/IMG_8477-1-1024x683.jpg 1024w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/09\/IMG_8477-1-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/09\/IMG_8477-1.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Ushuaia, mi\u00e9rcoles 6 de marzo de 2024.- Tom\u00f3 estado parlamentario el proyecto de Ley que busca atender las cuestiones de la salud mental en la adolescencia. La iniciativa, que lleva el n\u00famero de <a href=\"https:\/\/www.legistdf.gob.ar\/lp\/novedadesip\/Asuntos%20Entrados%202024\/As.%20N%BA%20019-24.pdf\" target=\"_blank\" rel=\"noopener\">asunto 019\/24<\/a>, es autor\u00eda de la legisladora Mar\u00eda Victoria Vuoto del Partido Justicialista y fue girado a la Comisi\u00f3n de Salud N\u00ba 5. En la propuesta, la Legisladora se\u00f1ala que se espera \u201casegurar el derecho a la protecci\u00f3n de la salud mental en la adolescencia de nuestra Provincia\u201d y propone una serie de pol\u00edticas p\u00fablicas \u201ccon un abordaje integral y con perspectiva de derechos\u201d.<\/span><\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\">En este sentido, el proyecto de Ley se\u00f1ala que la <a href=\"https:\/\/servicios.infoleg.gob.ar\/infolegInternet\/anexos\/110000-114999\/110778\/norma.htm\" target=\"_blank\" rel=\"noopener\">Ley nacional N\u00ba 26.061<\/a> contiene disposiciones sobre derecho a la salud. \u201cEl art\u00edculo 14, en su \u00faltimo p\u00e1rrafo, establece que tienen derecho a la atenci\u00f3n integral de su salud\u201d. Tambi\u00e9n menciona la <a href=\"https:\/\/servicios.infoleg.gob.ar\/infolegInternet\/anexos\/175000-179999\/175977\/norma.htm\" target=\"_blank\" rel=\"noopener\">Ley nacional N\u00ba 26.657<\/a> de Salud Mental. En el particular, \u201cprocura asegurar el derecho a la protecci\u00f3n de la salud mental de todas las personas, y el pleno goce de los derechos humanos de aquellas con padecimiento mental que se encuentran en el territorio nacional\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\">\u201cEs crucial abordar las necesidades de los adolescentes con condiciones de salud mental definidas. Evitar la institucionalizaci\u00f3n y la sobremedicalizaci\u00f3n, priorizar enfoques no farmacol\u00f3gicos y respetar los derechos de los ni\u00f1os de acuerdo con la Convenci\u00f3n de las Naciones Unidas sobre los Derechos del Ni\u00f1o y otros instrumentos de derechos humanos son clave para los adolescentes\u201d, sostiene Vuoto en los fundamentos del proyecto de Ley que ser\u00e1 analizado por la Comisi\u00f3n de Salud N\u00ba 5.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\"><a href=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/09\/IMG_8587.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-39680 size-medium\" title=\"Parlamento Juvenil 2023\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/09\/IMG_8587-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/09\/IMG_8587-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/09\/IMG_8587-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/09\/IMG_8587-1024x683.jpg 1024w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/09\/IMG_8587-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/09\/IMG_8587.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>El articulado de la propuesta se divide en cuatro cap\u00edtulos que abordan disposiciones generales y principios rectores; espacio donde crea el Programa de Prevenci\u00f3n y Asistencia en salud mental para la adolescencia y busca \u201casegurar el derecho a la prevenci\u00f3n, promoci\u00f3n y acceso a la salud mental\u201d de ese grupo etario en Tierra del Fuego.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\">Entre los objetivos del programa establece la promoci\u00f3n de la salud mental en las adolescencias, \u201cque comprende la intervenci\u00f3n sobre los determinantes sociales de la salud, favoreciendo la pr\u00e1ctica de conductas y la creaci\u00f3n de entornos saludables; el fortalecimiento de la identidad y autoestima de la persona y la generaci\u00f3n de espacios de participaci\u00f3n ciudadana\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\">Tambi\u00e9n propone \u201cdise\u00f1ar dispositivos coordinando y articulando diferentes \u00e1reas del Poder Ejecutivo, a fin de implementar pr\u00e1cticas educativas, culturales, deportivas, entre otras, promotoras de cuidados y salud\/salud mental de la adolescencia desde una perspectiva integral y de derechos\u201d. Y tambi\u00e9n determina capacitaciones abiertas a la comunidad y articulaci\u00f3n para procesos de formaci\u00f3n del recurso humano en Salud Mental Comunitaria, \u00abincluyendo la posibilidad que los adolescentes puedan desarrollar las habilidades necesarias para apoyar a sus amigos y amigas\u201d<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\">En otro articulado, la Legisladora propone la creaci\u00f3n de tres ejes de trabajo a los fines de una asistencia integral con una mesa Interinstitucional de prevenci\u00f3n y asistencia en Salud Mental para las adolescencias; un servicio de asistencia en Salud Mental; y de un dispositivo con el arte como recurso para el cuidado de la salud mental de adolescentes.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\"><a href=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2024\/03\/IMG_2115.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-41806 size-medium\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2024\/03\/IMG_2115-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2024\/03\/IMG_2115-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2024\/03\/IMG_2115-1024x683.jpg 1024w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2024\/03\/IMG_2115-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2024\/03\/IMG_2115-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2024\/03\/IMG_2115-1320x880.jpg 1320w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2024\/03\/IMG_2115.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Respecto de la mesa interinstitucional de prevenci\u00f3n y asistencia en Salud Mental para las adolescencias, funcionar\u00e1 en el \u00e1mbito de la Comisi\u00f3n Provincial de Salud Mental y Adicciones de la Provincia, \u201ccon el fin de establecer una estrategia integral para planificar, dise\u00f1ar y coordinar las pol\u00edticas p\u00fablicas de Prevenci\u00f3n y Asistencia de Salud Mental y Adicciones en Adolescentes\u201d. Vuoto considera que podr\u00e1n integrarla \u201cun integrante de las \u00e1reas o servicios que llevan adelante las pol\u00edticas de los adolescentes de los Ministerios de Jefatura de Gabinete; Ministerio de Salud; Ministerio de Educaci\u00f3n; Ministerio de Bienestar Ciudadano; Agencia de Innovaci\u00f3n de la Provincia de Tierra dcl Fuego o en los que en el futuro los reemplace y todo aquel representante del Poder Ejecutivo Provincial y de otras instituciones p\u00fablicas o privadas que Ia autoridad de aplicaci\u00f3n designe, tanto como mesa ejecutiva o ampliada, con el objetivo de poder llevar adelante las pol\u00edticas p\u00fablicas del Programa\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\">El articulado tambi\u00e9n garantiza \u201cel acceso a servicios de salud, respetando las pautas familiares y culturales reconocidas por la familia y la comunidad a la que pertenecen siempre que no constituyan peligro para su vida e integridad; programas de asistencia integral, rehabilitaci\u00f3n e integraci\u00f3n; el derecho de los adolescentes a contar con la informaci\u00f3n y orientaci\u00f3n; programas de atenci\u00f3n, orientaci\u00f3n y asistencia dirigidos a su familia; y programas de salud mental para adolescentes con un abordaje integral y con perspectiva de derechos\u201d sostiene en el art\u00edculo 11.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\">Tambi\u00e9n dispone de la creaci\u00f3n de un servicio de salud mental ambulatorio de Adolescentes con dos dispositivos de atenci\u00f3n: el dispositivo de atenci\u00f3n a la demanda espont\u00e1nea, donde se recepcionan las primeras consultas y, mediante una entrevista de evaluaci\u00f3n interdisciplinaria, se considera el tratamiento m\u00e1s adecuado para cada caso en particular: y el dispositivo ambulatorio ofrece tratamientos en salud mental a adolescentes a cargo de equipos interdisciplinarios\u201d. El equipo de intervenci\u00f3n deber\u00e1 conformarse con tres psic\u00f3logas\/os; un profesional de la psicopedagog\u00eda: un profesional del trabajo social; y un m\u00e9dico psiquiatra.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\"><a href=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2024\/03\/IMG_2264.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-41847 size-medium\" title=\"Parlamento Juvenil 2023\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2024\/03\/IMG_2264-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2024\/03\/IMG_2264-300x200.jpg 300w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2024\/03\/IMG_2264-1024x683.jpg 1024w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2024\/03\/IMG_2264-768x512.jpg 768w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2024\/03\/IMG_2264-160x107.jpg 160w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2024\/03\/IMG_2264-1320x880.jpg 1320w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2024\/03\/IMG_2264.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\u201cLas adolescencias en nuestra Provincia carecen de dispositivos o servicios p\u00fablicos de Salud Mental con perspectiva de adolescencias o espec\u00edficos en esta franja etaria, o est\u00e1n subordinados a otros servicios y en cuanto a condiciones edilicias de estos espacios, muchas veces no son \u00f3ptimas para poder desarrollar un proceso terap\u00e9utico, adem\u00e1s no se cuenta con una red de acompa\u00f1amiento y espacios de escucha\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;font-size: 12pt\">\u201cResulta imprescindible que nuestro ordenamiento jur\u00eddico asigne a la salud mental de ni\u00f1as, ni\u00f1os y adolescentes un adecuado marco normativo que d\u00e9 cuenta del escenario y las particularidades de este grupo de personas de manera de posibilitar la formulaci\u00f3n de pol\u00edticas p\u00fablicas id\u00f3neas que orienten las acciones de los diferentes actores gubernamentales, eviten el sufrimiento y protejan la salud mental de ni\u00f1as, ni\u00f1os y adolescentes\u201d, cierra en la fundamentaci\u00f3n del asunto 019\/24.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right\"><em>AT con im\u00e1genes de archivo<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ushuaia, mi\u00e9rcoles 6 de marzo de 2024.- Tom\u00f3 estado parlamentario el proyecto de Ley que busca atender las cuestiones de la salud mental en la adolescencia. La iniciativa, que lleva el n\u00famero de asunto 019\/24, es autor\u00eda de la legisladora Mar\u00eda Victoria Vuoto del Partido Justicialista y fue girado a la Comisi\u00f3n de Salud N\u00ba [&hellip;]<\/p>\n","protected":false},"author":352,"featured_media":39680,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[1446,78,2168,448,166,79,87],"class_list":["post-41910","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa","tag-adolescencias","tag-legislatura","tag-maria-victoria-vuoto","tag-proyecto-de-ley","tag-salud-mental","tag-tierra-del-fuego","tag-ushuaia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2023\/09\/IMG_8587.jpg","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/41910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/352"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=41910"}],"version-history":[{"count":1,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/41910\/revisions"}],"predecessor-version":[{"id":41911,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/41910\/revisions\/41911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media\/39680"}],"wp:attachment":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=41910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=41910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=41910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}