{"id":5908,"date":"2018-02-28T18:35:33","date_gmt":"2018-02-28T21:35:33","guid":{"rendered":"http:\/\/www.legistdf.gob.ar\/index.php\/2018\/02\/28\/sesion-preparatoria-designaron-autoridades-de-la-camara-para-2018\/"},"modified":"2018-02-28T21:25:28","modified_gmt":"2018-03-01T00:25:28","slug":"sesion-preparatoria-designaron-autoridades-de-la-camara-para-2018","status":"publish","type":"post","link":"https:\/\/www.legistdf.gob.ar\/index.php\/2018\/02\/28\/sesion-preparatoria-designaron-autoridades-de-la-camara-para-2018\/","title":{"rendered":"SESI\u00d3N PREPARATORIA: Designaron autoridades de la C\u00e1mara para 2018"},"content":{"rendered":"<p>Ushuaia, mi\u00e9rcoles 28 de febrero de 2018.- La sesi\u00f3n preparatoria determin\u00f3 la composici\u00f3n de autoridades para el 35\u00ba per\u00edodo ordinario de sesiones, con la vicepresidencia 1\u00aa, nuevamente a cargo de la legisladora del FPV &#8211; PJ Myriam Mart\u00ednez y de la legisladora de la UCR &#8211; Cambiemos, Liliana Mart\u00ednez Allende como vicepresidenta 2\u00aa. Ma\u00f1ana jueves, se realizar\u00e1 la sesi\u00f3n inaugural con el mensaje de la Dra. Rosana Bertone al Parlamento, iniciar\u00e1 a las 9. A continuaci\u00f3n, se concretar\u00e1 la primera sesi\u00f3n ordinaria, a las 13, propuesta emanada por el bloque del FPV \u2013 PJ.<\/p>\n<p>Andrea Rodr\u00edguez y Elio M\u00fcller, contin\u00faan como secretarios legislativo y administrativo, respectivamente. La Dra. Carolina Osta contin\u00faa como prosecretaria legislativa y la se\u00f1ora Mercedes Gauna como prosecretaria administrativa. Tambi\u00e9n se definieron los integrantes y autoridades de las comisiones permanentes de asesoramiento y de las comisiones especiales.<\/p>\n<pre><em>Con informaci\u00f3n de Prensa Legislativa\r\n\r\n<\/em><strong><a href=\"https:\/\/es-la.facebook.com\/PrensaLegislaturatdf\">\r\nFacebook<\/a> <a href=\"https:\/\/twitter.com\/PrensaLegisTDF\">Twitter<\/a> <a href=\"https:\/\/www.flickr.com\/photos\/prensalegistdf\/sets\/\">Flickr\r\n\r\n<\/a><\/strong>\r\n<strong>DIRECCI\u00d3N DE PRENSA Y DIFUSI\u00d3N INSTITUCIONAL LEGISLATURA DE TIERRA DEL FUEGO <\/strong><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Ushuaia, mi\u00e9rcoles 28 de febrero de 2018.- La sesi\u00f3n preparatoria determin\u00f3 la composici\u00f3n de autoridades para el 35\u00ba per\u00edodo ordinario de sesiones, con la vicepresidencia 1\u00aa, nuevamente a cargo de la legisladora del FPV &#8211; PJ Myriam Mart\u00ednez y de la legisladora de la UCR &#8211; Cambiemos, Liliana Mart\u00ednez Allende como vicepresidenta 2\u00aa. Ma\u00f1ana jueves, [&hellip;]<\/p>\n","protected":false},"author":352,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-5908","post","type-post","status-publish","format-standard","hentry","category-prensa"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/5908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/352"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=5908"}],"version-history":[{"count":2,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/5908\/revisions"}],"predecessor-version":[{"id":5910,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/5908\/revisions\/5910"}],"wp:attachment":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=5908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=5908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=5908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}