{"id":6143,"date":"2018-03-14T14:07:41","date_gmt":"2018-03-14T17:07:41","guid":{"rendered":"http:\/\/www.legistdf.gob.ar\/?p=6143"},"modified":"2018-03-15T14:56:12","modified_gmt":"2018-03-15T17:56:12","slug":"justicia-arcando-celebro-la-inauguracion-del-edificio-propio-de-la-defensoria-genera-l-de-la-nacion-en-rio-grande","status":"publish","type":"post","link":"https:\/\/www.legistdf.gob.ar\/index.php\/2018\/03\/14\/justicia-arcando-celebro-la-inauguracion-del-edificio-propio-de-la-defensoria-genera-l-de-la-nacion-en-rio-grande\/","title":{"rendered":"JUSTICIA: Arcando celebr\u00f3 la inauguraci\u00f3n del edificio propio de la Defensor\u00eda General de la Naci\u00f3n en R\u00edo Grande"},"content":{"rendered":"<p><strong>R\u00edo Grande, mi\u00e9rcoles 14 de marzo de 2018.- El Presidente del Parlamento, vicegobernador Juan Carlos Arcando particip\u00f3, esta ma\u00f1ana, de la inauguraci\u00f3n del edificio de la Defensor\u00eda General de la Naci\u00f3n en R\u00edo Grande. El acto fue presidido por la Defensora General de la Naci\u00f3n, Dra. Estela Maris Mart\u00ednez y el defensor Oficial ante el Juzgado Federal en la ciudad, Dr. Guillermo Garone. El Vicegobernador destac\u00f3 que los trabajadores de la repartici\u00f3n cuentan \u2013desde hoy- con un edificio \u201cque re\u00fane las condiciones \u00f3ptimas para ejercer las funciones de la instituci\u00f3n\u201d y evalu\u00f3 que se trata de un \u201caporte cuyos beneficiarios adem\u00e1s de los trabajadores de la repartici\u00f3n, ser\u00e1n los vecinos que concurran a la Defensor\u00eda\u201d.<\/strong><\/p>\n<p>\u201cLa Defensor\u00eda es una instituci\u00f3n de defensa y protecci\u00f3n de derechos humanos que garantiza el acceso a Justicia y asistencia jur\u00eddica integral. Inicia toda medida tendiente a la protecci\u00f3n y defensa de los derechos de las personas, en especial de quienes se encuentren en situaci\u00f3n de vulnerabilidad. En Tierra del Fuego las m\u00e1s requeridas son las referidas a los jubilados y pensionados de ANSES, en lo que respecta al reclamo por la Reparaci\u00f3n Hist\u00f3rica; los reclamos por la atenci\u00f3n de las Obra Sociales Nacionales, entre otras\u201d. Am\u00e9n de ello, tambi\u00e9n aporta soluciones en cuestiones aduaneras, impositivas y tratan \u201ctemas cuando los vecinos no tienen suficientes recursos para recurrir a un abogado\u201d.<\/p>\n<p>En este sentido, Arcando consider\u00f3 que es importante el acompa\u00f1amiento de la Defensor\u00eda a los vecinos, en el \u201cresguardo de sus derechos\u201d que est\u00e1n expresados en la letra constitucional de la Naci\u00f3n. Luego, junto al titular de la Ciudad y empleados de la repartici\u00f3n, recorri\u00f3 las distintas instalaciones del edificio, que adem\u00e1s, est\u00e1 dise\u00f1ado para impartir capacitaciones en l\u00ednea a trav\u00e9s de videoconferencia, entre otras prestaciones.<\/p>\n<p>En otro orden, la Dra. Mart\u00ednez refiri\u00f3 al anterior emplazamiento de la Defensor\u00eda y sostuvo que \u201cnos parec\u00eda incorrecto que funcionara en un edificio hist\u00f3rico y que el personal trabajara en condiciones incorrectas\u201d dijo esta ma\u00f1ana, durante el acto de inauguraci\u00f3n de las instalaciones que se ubican en Ricardo Rojas al 900. \u201cSi bien es cierto que Ushuaia es la m\u00e1s conocida, en R\u00edo Grande tenemos el s\u00edmbolo de lo que es el sur, vivir en el sur y luchar en un lugar que, sin embargo, guarda el significado de lo que es la Rep\u00fablica. El significado del federalismo\u201d, se\u00f1al\u00f3. Tambi\u00e9n anot\u00f3 que la ciudad tiene la cercan\u00eda con las Islas Malvinas: \u201cEs a estos lugares, a los que hay que darles las condiciones m\u00ednimas de confort\u201d, agreg\u00f3 en referencia a las comodidades que ofrecen las instalaciones.<\/p>\n<p>En di\u00e1logo con Prensa Legislativa, el Dr. Garone detall\u00f3 que entre las funciones de la repartici\u00f3n, abordan \u201cdelitos de contrabando, narcotr\u00e1fico, infracciones aduaneras\u201d, en el \u00e1mbito criminal. En cuanto a la faz civil, la Defensor\u00eda atiende asuntos sobre jubilaciones y pensiones a nivel nacional, reclamos ante la AFIP y ANSES, el resguardo de los derechos civiles amparados en la Constituci\u00f3n Nacional. Aclar\u00f3 asimismo, que no atienden cuestiones de la faz provincial por no ser \u00f3rbita de esa Defensor\u00eda. \u201cNosotros, en el \u00e1mbito federal, trabajamos en la competencia originaria de la Naci\u00f3n\u201d, apunt\u00f3.<\/p>\n<p>Consultado sobre la importancia de la instituci\u00f3n para los fueguinos, Garone consider\u00f3 que es destacada ya que \u201ctrabajamos desde el aseguramiento de los derechos de los ciudadanos\u201d, lo que ejemplific\u00f3 con salud. \u201cNosotros creemos que, desde la defensa, trabajamos para proteger esos derechos ante el Juzgado y el juez, para que acompa\u00f1e la tutela de esos derechos\u201d, enumer\u00f3.<\/p>\n<p>Cabe se\u00f1alar que la Defensor\u00eda funciona hace a\u00f1os en R\u00edo Grande, y que el nuevo emplazamiento, ofrece condiciones de accesibilidad apropiadas para los vecinos y que se pueda \u201cbrindar el servicio de Justicia\u201d con calidad, describi\u00f3 el letrado. La p\u00e1gina web es <a href=\"http:\/\/www.mpd.gob.ar\/\">www.mpd.gob.ar<\/a>, donde se puede acceder a toda la informaci\u00f3n orientativa para los usuarios.<\/p>\n<p>Participaron del acto, el ministro de Educaci\u00f3n de la Provincia, profesor Diego Romero; el Intendente de R\u00edo Grande, profesor Gustavo Melella; el concejal Paulino Rossi; representantes de la Justicia provincial y de las fuerzas Armadas y de Seguridad.<\/p>\n<pre><em>Con informaci\u00f3n y fotograf\u00edas de Prensa Legislativa<\/em><\/pre>\n<pre><strong><a href=\"https:\/\/es-la.facebook.com\/PrensaLegislaturatdf\">\r\nFacebook<\/a> <a href=\"https:\/\/twitter.com\/PrensaLegisTDF\">Twitter<\/a> <a href=\"https:\/\/www.flickr.com\/photos\/prensalegistdf\/sets\/\">Flickr\r\n\r\n<\/a><\/strong>\r\n<strong>DIRECCI\u00d3N DE PRENSA Y DIFUSI\u00d3N INSTITUCIONAL LEGISLATURA DE TIERRA DEL FUEGO <\/strong><\/pre>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-6143 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2018\/03\/14\/justicia-arcando-celebro-la-inauguracion-del-edificio-propio-de-la-defensoria-genera-l-de-la-nacion-en-rio-grande\/1-88\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/03\/1-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/03\/1-1-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/03\/1-1-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2018\/03\/14\/justicia-arcando-celebro-la-inauguracion-del-edificio-propio-de-la-defensoria-genera-l-de-la-nacion-en-rio-grande\/2-88\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/03\/2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/03\/2-1-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/03\/2-1-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2018\/03\/14\/justicia-arcando-celebro-la-inauguracion-del-edificio-propio-de-la-defensoria-genera-l-de-la-nacion-en-rio-grande\/3-77\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/03\/3-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/03\/3-1-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/03\/3-1-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2018\/03\/14\/justicia-arcando-celebro-la-inauguracion-del-edificio-propio-de-la-defensoria-genera-l-de-la-nacion-en-rio-grande\/4-72\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/03\/4-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/03\/4-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/03\/4-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2018\/03\/14\/justicia-arcando-celebro-la-inauguracion-del-edificio-propio-de-la-defensoria-genera-l-de-la-nacion-en-rio-grande\/6-49\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/03\/6-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/03\/6-1-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/03\/6-1-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2018\/03\/14\/justicia-arcando-celebro-la-inauguracion-del-edificio-propio-de-la-defensoria-genera-l-de-la-nacion-en-rio-grande\/7-35\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/03\/7-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/03\/7-1-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/03\/7-1-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2018\/03\/14\/justicia-arcando-celebro-la-inauguracion-del-edificio-propio-de-la-defensoria-genera-l-de-la-nacion-en-rio-grande\/5-69\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/03\/5-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/03\/5-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/03\/5-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>R\u00edo Grande, mi\u00e9rcoles 14 de marzo de 2018.- El Presidente del Parlamento, vicegobernador Juan Carlos Arcando particip\u00f3, esta ma\u00f1ana, de la inauguraci\u00f3n del edificio de la Defensor\u00eda General de la Naci\u00f3n en R\u00edo Grande. El acto fue presidido por la Defensora General de la Naci\u00f3n, Dra. Estela Maris Mart\u00ednez y el defensor Oficial ante el [&hellip;]<\/p>\n","protected":false},"author":352,"featured_media":6144,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-6143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/03\/1-1.jpg","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/6143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/352"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=6143"}],"version-history":[{"count":4,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/6143\/revisions"}],"predecessor-version":[{"id":6186,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/6143\/revisions\/6186"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media\/6144"}],"wp:attachment":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=6143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=6143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=6143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}