{"id":8785,"date":"2018-08-15T15:03:47","date_gmt":"2018-08-15T18:03:47","guid":{"rendered":"http:\/\/www.legistdf.gob.ar\/?p=8785"},"modified":"2018-08-15T15:04:38","modified_gmt":"2018-08-15T18:04:38","slug":"deportes-arcando-recibio-a-pilotos-que-participaran-del-gran-premio-de-la-hermandad-2018","status":"publish","type":"post","link":"https:\/\/www.legistdf.gob.ar\/index.php\/2018\/08\/15\/deportes-arcando-recibio-a-pilotos-que-participaran-del-gran-premio-de-la-hermandad-2018\/","title":{"rendered":"DEPORTES: Arcando recibi\u00f3 a pilotos que participar\u00e1n del Gran Premio de la Hermandad 2018"},"content":{"rendered":"<p><strong>Ushuaia, mi\u00e9rcoles 15 de agosto de 2018.- El vicegobernador Juan Carlos Arcando recibi\u00f3 en sede de Presidencia, a corredores automovil\u00edsticos que participar\u00e1n del Gran Premio de la Hermandad 2018. \u201cPara nosotros es una gran satisfacci\u00f3n poder seguir acompa\u00f1ando a los deportistas de Tierra del Fuego\u201d, dijo el titular del Parlamento.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>\u201cHoy recib\u00ed a estos dos pilotos de Ushuaia, que van a participar del Gran Premio de la Hermandad 2018. Dos pilotos con trayectoria en esta carrera y en otras que se realizan a nivel provincial\u201d, cont\u00f3 Arcando. Resalt\u00f3 en este sentido que, \u201ccomo siempre, la instituci\u00f3n acompa\u00f1a dentro de sus posibilidades, esta participaci\u00f3n\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>El Vicegobernador record\u00f3 que este a\u00f1o, la competencia \u201cha tenido el reconocimiento del Senado de la Naci\u00f3n, con un acto que se llev\u00f3 adelante hace diez d\u00edas atr\u00e1s, encabezado por el presidente de la Comisi\u00f3n de Deportes de la C\u00e1mara alta, el senador fueguino Julio Catal\u00e1n Magni\u201d. Afirm\u00f3 que \u201ceso significa que esta carrera ya es reconocida a nivel nacional por todos aquellos que tienen responsabilidades pol\u00edticas. Para nosotros es una gran satisfacci\u00f3n poder seguir acompa\u00f1ando a los deportistas de Tierra del Fuego\u201d, destac\u00f3 Juan Carlos Arcando.<\/p>\n<p>&nbsp;<\/p>\n<p>Julio Andrade, uno de los participantes recibido por el Vicegobernador, agradeci\u00f3 a Arcando ya que \u201csiempre colabora en todo lo que puede\u201d. Por eso le entregaron una placa de reconocimiento de parte de la Asociaci\u00f3n de Rally Austral. Andrade explic\u00f3 que \u201cse hace muy dif\u00edcil la participaci\u00f3n nuestra en este tipo de competencias, por los costos que acarrea, y sin la ayuda de instituciones como en este caso la Legislatura, ser\u00eda imposible que pudi\u00e9ramos participar en esta competencia. Por ello estamos muy agradecidos al vicegobernador Juan Carlos Arcando\u201d, concluy\u00f3.<\/p>\n<p>&nbsp;<\/p>\n<p>Por su parte Cristian Leal cont\u00f3 a Prensa Legislativa que \u201cvamos a competir en este Gran Premio de la Hermandad 2018, hace diez a\u00f1os que venimos participando de este encuentro\u201d. Respecto a lo que espera para la competencia que se llevar\u00e1 a cabo este fin de semana, asegur\u00f3 que \u201ctenemos muy buenas expectativas, ya que tenemos un auto muy competitivo\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>En este sentido, el piloto ushuaiense explic\u00f3 que \u201cvoy a participar con mi hermano, que navega desde que arranqu\u00e9 con el automovilismo. Esperamos hacer una buena carrera\u201d. Respecto de su visita al titular del Parlamento, dijo: \u201cQuiero resaltar y agradecer a la gente que apoya el deporte motor y en este caso en particular al vicegobernador Juan Carlos Arcando, que siempre est\u00e1 presente y dispuesto a colaborar con este tipo de actividades deportivas\u201d, cerr\u00f3 Leal.<\/p>\n<p>&nbsp;<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-8785 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2018\/08\/15\/deportes-arcando-recibio-a-pilotos-que-participaran-del-gran-premio-de-la-hermandad-2018\/img_3352\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/08\/IMG_3352-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/08\/IMG_3352-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/08\/IMG_3352-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2018\/08\/15\/deportes-arcando-recibio-a-pilotos-que-participaran-del-gran-premio-de-la-hermandad-2018\/img_3356\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/08\/IMG_3356-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/08\/IMG_3356-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/08\/IMG_3356-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2018\/08\/15\/deportes-arcando-recibio-a-pilotos-que-participaran-del-gran-premio-de-la-hermandad-2018\/img_3359\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/08\/IMG_3359-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/08\/IMG_3359-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/08\/IMG_3359-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Ushuaia, mi\u00e9rcoles 15 de agosto de 2018.- El vicegobernador Juan Carlos Arcando recibi\u00f3 en sede de Presidencia, a corredores automovil\u00edsticos que participar\u00e1n del Gran Premio de la Hermandad 2018. \u201cPara nosotros es una gran satisfacci\u00f3n poder seguir acompa\u00f1ando a los deportistas de Tierra del Fuego\u201d, dijo el titular del Parlamento. \u00a0 \u201cHoy recib\u00ed a estos [&hellip;]<\/p>\n","protected":false},"author":352,"featured_media":8787,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[291,428,97,78,87],"class_list":["post-8785","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa","tag-deportes","tag-gran-premio-de-la-hermandad","tag-juan-carlos-arcando","tag-legislatura","tag-ushuaia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/08\/IMG_3356.jpg","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/8785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/352"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=8785"}],"version-history":[{"count":1,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/8785\/revisions"}],"predecessor-version":[{"id":8789,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/8785\/revisions\/8789"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media\/8787"}],"wp:attachment":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=8785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=8785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=8785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}