{"id":8893,"date":"2018-08-21T13:55:01","date_gmt":"2018-08-21T16:55:01","guid":{"rendered":"http:\/\/www.legistdf.gob.ar\/?p=8893"},"modified":"2018-08-21T13:55:01","modified_gmt":"2018-08-21T16:55:01","slug":"educacion-de-interes-provincial-el-25o-aniversario-del-colegio-nacional-ushuaia","status":"publish","type":"post","link":"https:\/\/www.legistdf.gob.ar\/index.php\/2018\/08\/21\/educacion-de-interes-provincial-el-25o-aniversario-del-colegio-nacional-ushuaia\/","title":{"rendered":"EDUCACI\u00d3N: De inter\u00e9s provincial el 25\u00ba aniversario del Colegio Nacional Ushuaia"},"content":{"rendered":"<p><strong>Ushuaia, martes 21 de agosto de 2018.-\u00a0\u00a0El Colegio Nacional Ushuaia conmemor\u00f3 su 25\u00ba aniversario, el viernes \u00faltimo. Los legisladores Liliana Mart\u00ednez Allende (UCR \u2013 Cambiemos), M\u00f3nica Urquiza y Pablo Villegas (MPF), entregaron la declaraci\u00f3n de inter\u00e9s provincial a las actividades de la instituci\u00f3n en reconocimiento por su amplia trayectoria en la formaci\u00f3n\u00a0 de estudiantes.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>El acto se realiz\u00f3 en el gimnasio del Ushuaia Rugby Club y cont\u00f3 con la presencia de autoridades de la Provincia, Concejales y de las fuerzas de Seguridad. Los Parlamentarios participaron de la celebraci\u00f3n y entregaron la resoluci\u00f3n de Presidencia N\u00ba 1003\/18 sobre la declaraci\u00f3n de inter\u00e9s provincial, sancionada por la C\u00e1mara con el apoyo de la totalidad de los Parlamentarios.<\/p>\n<p>&nbsp;<\/p>\n<p>Cabe recordar, que el 16 de agosto de 1993 un grupo de padres buscaba la mejor educaci\u00f3n formal para sus hijos. De esa forma, firmaron el acta fundamental del Colegio Nacional Ushuaia con la apertura del nivel secundario, desde all\u00ed formularon una educaci\u00f3n laica que creci\u00f3 e incorpor\u00f3 la educaci\u00f3n primaria, hace 8 a\u00f1os.<\/p>\n<p>Durante el acto, se entregaron sendos reconocimientos a los integrantes de la primera comisi\u00f3n directiva de la instituci\u00f3n, como as\u00ed tambi\u00e9n se destac\u00f3 la participaci\u00f3n de integrantes del Colegio Nacional de Buenos Aires. En otro pasaje del emotivo acto, que cont\u00f3 con alumnos de los primeros a\u00f1os en la interpretaci\u00f3n en lenguaje de se\u00f1as del Himno Nacional argentino y la Marcha de Malvinas, exalumnos del establecimiento \u2013ahora docentes de esa Casa- rese\u00f1aron la historia del Colegio Nacional.<\/p>\n<p>&nbsp;<\/p>\n<p>El colegio en su nivel secundario, ofrece un amplio espacio curricular desde biolog\u00eda; f\u00edsica; portugu\u00e9s; m\u00fasica; educaci\u00f3n tecnol\u00f3gica; ingles, entre otros.<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-8893 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2018\/08\/21\/educacion-de-interes-provincial-el-25o-aniversario-del-colegio-nacional-ushuaia\/img_3966\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/08\/IMG_3966-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/08\/IMG_3966-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/08\/IMG_3966-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2018\/08\/21\/educacion-de-interes-provincial-el-25o-aniversario-del-colegio-nacional-ushuaia\/img_3970\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/08\/IMG_3970-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/08\/IMG_3970-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/08\/IMG_3970-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.legistdf.gob.ar\/index.php\/2018\/08\/21\/educacion-de-interes-provincial-el-25o-aniversario-del-colegio-nacional-ushuaia\/img_4022\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/08\/IMG_4022-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/08\/IMG_4022-150x150.jpg 150w, https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/08\/IMG_4022-64x64.jpg 64w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ushuaia, martes 21 de agosto de 2018.-\u00a0\u00a0El Colegio Nacional Ushuaia conmemor\u00f3 su 25\u00ba aniversario, el viernes \u00faltimo. Los legisladores Liliana Mart\u00ednez Allende (UCR \u2013 Cambiemos), M\u00f3nica Urquiza y Pablo Villegas (MPF), entregaron la declaraci\u00f3n de inter\u00e9s provincial a las actividades de la instituci\u00f3n en reconocimiento por su amplia trayectoria en la formaci\u00f3n\u00a0 de estudiantes. &nbsp; [&hellip;]<\/p>\n","protected":false},"author":352,"featured_media":8896,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[219,80,78,155,144,106,87],"class_list":["post-8893","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa","tag-colegio-nacional-ushuaia","tag-educacion","tag-legislatura","tag-liliana-martinez-allende","tag-monica-urquiza","tag-pablo-villegas","tag-ushuaia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.legistdf.gob.ar\/wp-content\/uploads\/2018\/08\/IMG_4022.jpg","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/8893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/352"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=8893"}],"version-history":[{"count":1,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/8893\/revisions"}],"predecessor-version":[{"id":8897,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/8893\/revisions\/8897"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media\/8896"}],"wp:attachment":[{"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=8893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=8893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legistdf.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=8893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}